{"id":840,"date":"2020-11-04T10:53:54","date_gmt":"2020-11-04T10:53:54","guid":{"rendered":"https:\/\/webdev.locaterisk.com\/?page_id=840"},"modified":"2022-07-14T16:14:27","modified_gmt":"2022-07-14T16:14:27","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/locaterisk.com\/fr\/datenschutz\/","title":{"rendered":"Confidentialit\u00e9"},"content":{"rendered":"<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:750px\">\n<div style=\"color:white;\"><h1>D\u00e9claration de confidentialit\u00e9<\/h1>\n<p>Nous sommes heureux que vous visitiez notre site web. La protection de votre vie priv\u00e9e est tr\u00e8s importante pour nous et nous souhaitons que vous vous sentiez en s\u00e9curit\u00e9 lors de l'utilisation de nos pages. C'est pourquoi nous traitons vos donn\u00e9es de mani\u00e8re confidentielle et conform\u00e9ment aux dispositions l\u00e9gales en mati\u00e8re de protection des donn\u00e9es et \u00e0 la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es.<\/p>\n<h3>1) le nom et l'adresse du responsable<\/h3>\n<p>Le responsable au sens de la l\u00e9gislation sur la protection des donn\u00e9es, en particulier du r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD) de l'UE, est :<\/p>\n<p>LocateRisk GmbH<br>6, rue Heinrich-Hertz<br>64295 Darmstadt<br>Allemagne<br>Directeur : Lukas Baumann<br>Courrier \u00e9lectronique : info@LocateRisk.com<br>T\u00e9l\u00e9phone : +49 6151 6290246<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>2. collecte d'informations g\u00e9n\u00e9rales lors de la visite de notre site web<\/h3>\n\n<h4>a. la nature et la finalit\u00e9 du traitement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Lorsque vous acc\u00e9dez \u00e0 notre site web, c'est-\u00e0-dire lorsque vous ne vous enregistrez pas ou ne transmettez pas d'informations d'une autre mani\u00e8re, des informations de nature g\u00e9n\u00e9rale sont automatiquement collect\u00e9es. Ces informations (fichiers journaux du serveur) comprennent par exemple le type de navigateur web, le syst\u00e8me d'exploitation utilis\u00e9, le nom de domaine de votre fournisseur de services Internet, votre adresse IP et d'autres informations similaires. <\/p>\n<p>Elles sont notamment trait\u00e9es aux fins suivantes :<\/p>\n<ul>\n<ul style=\"list-style-type: disc;  list-style-position: inside;font-size: 1.6em; line-height: 130%\">\n<li>Assurer une connexion sans probl\u00e8me du site web,<\/li>\n<li>Assurer une bonne utilisation de notre site web,<\/li>\n<li>l'\u00e9valuation de la s\u00e9curit\u00e9 et de la stabilit\u00e9 du syst\u00e8me, et<\/li>\n<li>pour optimiser notre site web.<\/li>\n<\/ul>\n<p>Nous n'utilisons pas vos donn\u00e9es pour tirer des conclusions sur votre personne. Les informations de ce type sont \u00e9ventuellement \u00e9valu\u00e9es statistiquement de mani\u00e8re anonyme afin d'optimiser notre site Internet et la technique qui le sous-tend. <\/p>\n<p><\/p><h4>b. Base juridique et int\u00e9r\u00eat l\u00e9gitime :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Le traitement est effectu\u00e9 conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point f), du RGPD, sur la base de notre int\u00e9r\u00eat l\u00e9gitime \u00e0 am\u00e9liorer la stabilit\u00e9 et la fonctionnalit\u00e9 de notre site web.<\/p>\n<p><\/p><h4>c. R\u00e9cepteur :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les destinataires des donn\u00e9es sont, le cas \u00e9ch\u00e9ant, des prestataires de services techniques qui agissent en tant que sous-traitants pour l'exploitation et la maintenance de notre site web.<\/p>\n<p><\/p><h4>d. Transfert de pays tiers :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les donn\u00e9es collect\u00e9es peuvent \u00eatre transf\u00e9r\u00e9es vers les pays tiers suivants : aucun.<\/p>\n<p>Les garanties de protection des donn\u00e9es suivantes sont disponibles : <\/p>\n<p><\/p><h4>d. Dur\u00e9e de conservation :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les donn\u00e9es sont supprim\u00e9es d\u00e8s qu'elles ne sont plus n\u00e9cessaires aux fins pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es. C'est en principe le cas pour les donn\u00e9es qui servent \u00e0 la mise \u00e0 disposition du site web, lorsque la session respective est termin\u00e9e. <\/p>\n<p> En cas d'enregistrement des donn\u00e9es dans des fichiers journaux, cela se produit au plus tard apr\u00e8s 14 jours. Un stockage au-del\u00e0 de ce d\u00e9lai est possible. Dans ce cas, les adresses IP des utilisateurs sont rendues anonymes, de sorte qu'une attribution du client appelant n'est plus possible.<\/p>\n<p><\/p><h4>e. Mise \u00e0 disposition prescrite ou n\u00e9cessaire :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>La mise \u00e0 disposition des donn\u00e9es personnelles susmentionn\u00e9es n'est pas prescrite par la loi ou par un contrat. Toutefois, sans l'adresse IP, le service et le fonctionnement de notre site web ne sont pas garantis. En outre, certains services et prestations peuvent ne pas \u00eatre disponibles ou \u00eatre limit\u00e9s. Pour cette raison, toute opposition est exclue. <\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>3. utilisation de cookies<\/h3>\n<p>Comme de nombreux autres sites web, nous utilisons \u00e9galement des \"cookies\". Les cookies sont de petits fichiers texte qui sont enregistr\u00e9s sur votre terminal (ordinateur portable, tablette, smartphone ou autre) lorsque vous visitez notre site web. <\/p>\n<p>Vous pouvez supprimer des cookies individuels ou l'ensemble des cookies. En outre, vous pouvez obtenir des informations et des instructions sur la mani\u00e8re de supprimer ces cookies ou de bloquer leur enregistrement au pr\u00e9alable. Selon le fournisseur de votre navigateur, vous trouverez les informations n\u00e9cessaires en cliquant sur les liens ci-dessous :<\/p>\n<ul>\n<ul style=\"list-style-type: disc;margin-left:20px;font-size: 1.6em; line-height: 130%\">\n\n<li>Mozilla Firefox :<br>\n<a href=\"https:\/\/support.mozilla.org\/de\/kb\/cookies-loeschen-daten-von-websites-entfernen\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/support.mozilla.org\/de\/kb\/cookies-loeschen-daten-von-websites-entfernen<\/a><\/li>\n<li>Internet Explorer :<br>\n<a href=\"https:\/\/support.microsoft.com\/de-de\/help\/17442\/windows-internet-explorer-delete-manage-cookies\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/support.microsoft.com\/de-de\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/a><\/li>\n<li>Google Chrome :<br>\n<a href=\"https:\/\/support.google.com\/accounts\/answer\/61416?hl=de\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/support.google.com\/accounts\/answer\/61416?hl=de<\/a><\/li>\n<li>Op\u00e9ra :<br>\n<a href=\"http:\/\/www.opera.com\/de\/help\" target=\"_blank\" rel=\"nofollow noopener\">http:\/\/www.opera.com\/de\/help<\/a><\/li>\n<li>Safari :<br>\n<a href=\"https:\/\/support.apple.com\/kb\/PH17191?locale=de_DE&amp;viewlocale=de_DE\" target=\"_blank\" rel=\"nofollow noopener\">https:\/\/support.apple.com\/kb\/PH17191?locale=de_DE&amp;viewlocale=de_DE<\/a><\/li>\n<\/ul>\n<p><\/p><h4>3.1 Dur\u00e9e de conservation et cookies utilis\u00e9s :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Dans la mesure o\u00f9 vous nous autorisez \u00e0 utiliser des cookies par le biais des param\u00e8tres de votre navigateur ou de votre consentement, les cookies suivants peuvent \u00eatre utilis\u00e9s sur nos pages web :<\/p>\n<p><b>Cookies fonctionnels :<\/b>\n<br>Nom : CONSENT\n<br>Validit\u00e9 : 2 ans\n<br>Fonction : Suivi du consentement des cookies\n<br>\n<br>\n<br>Lorsque vous consultez notre site web, les cookies suivants sont enregistr\u00e9s dans la m\u00e9moire tampon de votre navigateur apr\u00e8s votre accord.\n<br>\n<br>Nom : _ga\n<br>fournisseur de services :  Google Analytics\n<br>Objectif : Ce cookie est utilis\u00e9 pour collecter des informations sur la mani\u00e8re dont les visiteurs utilisent notre site web. Nous utilisons ces informations pour cr\u00e9er des rapports et nous aider \u00e0 am\u00e9liorer le site. Les cookies collectent les informations de mani\u00e8re anonyme, y compris le nombre de visiteurs du site, d'o\u00f9 les visiteurs sont venus sur le site et les pages qu'ils ont visit\u00e9es. Le cookie _ga sert \u00e0 distinguer les utilisateurs.\n<br>Date d'expiration : 2 ans\n<br>\n<br>Nom : _gld\n<br>fournisseur de services :  Google Analytics\n<br>Objectif : Ce cookie est utilis\u00e9 pour collecter des informations sur la mani\u00e8re dont les visiteurs utilisent notre site web. Nous utilisons ces informations pour cr\u00e9er des rapports et nous aider \u00e0 am\u00e9liorer le site. Les cookies collectent les informations de mani\u00e8re anonyme, y compris le nombre de visiteurs du site, d'o\u00f9 les visiteurs sont venus sur le site et les pages qu'ils ont visit\u00e9es. Le cookie _gid sert \u00e0 distinguer les utilisateurs.\n<br>Date d'expiration : 24 heures\n<br>\n<br>Nom : _gat\n<br>fournisseur de services :  Google Analytics\n<br>Objectif : Ce cookie est utilis\u00e9 pour collecter des informations sur la mani\u00e8re dont les visiteurs utilisent notre site web. Nous utilisons ces informations pour cr\u00e9er des rapports et nous aider \u00e0 am\u00e9liorer le site. Les cookies collectent les informations de mani\u00e8re anonyme, y compris le nombre de visiteurs du site, d'o\u00f9 les visiteurs sont venus sur le site et les pages qu'ils ont visit\u00e9es. Le cookie _gat, ralentit le taux de requ\u00eates.\n<br>Date d'expiration : 1 minute\n<br>\n<br>Remarques et possibilit\u00e9s d'opposition (opt-out) : Outils de suivi<\/p>\n<p><\/p><h3>3.2 Cookies techniquement n\u00e9cessaires <\/h3>\n<p>Nous utilisons des cookies pour rendre notre site web plus convivial. Certains \u00e9l\u00e9ments de notre site Internet exigent que le navigateur appelant puisse \u00eatre identifi\u00e9 m\u00eame apr\u00e8s un changement de page.<\/p>\n<p>Le but de l'utilisation de cookies techniquement n\u00e9cessaires est de simplifier l'utilisation des sites web pour les utilisateurs. Certaines fonctions de notre site Internet ne peuvent pas \u00eatre propos\u00e9es sans l'utilisation de cookies. Pour celles-ci, il est n\u00e9cessaire que le navigateur soit reconnu m\u00eame apr\u00e8s un changement de page.<\/p>\n<p>Nous avons besoin de cookies pour les applications suivantes :<\/p>\n<p>- Reprise des param\u00e8tres linguistiques<br>- M\u00e9moriser des termes de recherche<\/p>\n<p><\/p><h4>3.2.1 Base juridique et int\u00e9r\u00eat l\u00e9gitime : <\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Le traitement est effectu\u00e9 conform\u00e9ment \u00e0 l'article 6, paragraphe 1, point f), du RGPD, sur la base de notre int\u00e9r\u00eat l\u00e9gitime \u00e0 concevoir notre site web de mani\u00e8re conviviale.<\/p>\n<p><\/p><h4>3.2.2 Destinataires : <\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les destinataires des donn\u00e9es sont, le cas \u00e9ch\u00e9ant, des prestataires de services techniques qui agissent en tant que sous-traitants pour l'exploitation et la maintenance de notre site web.<\/p>\n<p><\/p><h4>3.2.3 Transfert de pays tiers :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les donn\u00e9es collect\u00e9es peuvent \u00eatre transf\u00e9r\u00e9es vers les pays tiers suivants : aucun.<\/p>\n<p>Les garanties de protection des donn\u00e9es suivantes sont disponibles : <\/p>\n<p><\/p><h4>3.2.4 Mise \u00e0 disposition prescrite ou n\u00e9cessaire :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>La mise \u00e0 disposition des donn\u00e9es personnelles susmentionn\u00e9es n'est pas prescrite par la loi ou par un contrat. Toutefois, sans ces donn\u00e9es, le service et le fonctionnement de notre site web ne sont pas garantis. En outre, certains services et prestations peuvent ne pas \u00eatre disponibles ou \u00eatre limit\u00e9s.<\/p>\n<p><\/p><h4>3.2.5 Contradiction<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Lisez \u00e0 ce sujet les informations sur votre droit d'opposition selon l'article 21 du RGPD ci-dessous.<\/p>\n\n<p><\/p><h3>3.3 Cookies non n\u00e9cessaires d'un point de vue technique<\/h3>\n<p>Par ailleurs, nous utilisons des cookies pour mieux adapter l'offre de notre site aux int\u00e9r\u00eats de nos visiteurs ou pour l'am\u00e9liorer de mani\u00e8re g\u00e9n\u00e9rale sur la base d'\u00e9valuations statistiques.<\/p>\n<p>Pour savoir quels fournisseurs utilisent des cookies, veuillez consulter les informations ci-dessous sur les technologies de pr\u00e9sentation, de suivi, de remarketing et d'analyse web utilis\u00e9es.<\/p>\n<h4>3.3.1 Base juridique :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>La base juridique de ces traitements est \u00e0 chaque fois votre consentement, art. 6, alin\u00e9a 1, lettre a du RGPD.<\/p>\n<h4>3.3.2 Destinataires :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les destinataires des donn\u00e9es sont, le cas \u00e9ch\u00e9ant, des prestataires de services techniques qui agissent en tant que sous-traitants pour l'exploitation et la maintenance de notre site web. <\/p>\n<p>Pour conna\u00eetre les autres destinataires, veuillez consulter les informations ci-dessous sur les technologies de pr\u00e9sentation, de suivi, de remarketing et d'analyse web utilis\u00e9es.<\/p>\n<h4>3.3.3 Transfert de pays tiers :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Vous trouverez des informations \u00e0 ce sujet dans les listes des diff\u00e9rents fournisseurs de pr\u00e9sentation, de suivi, de remarketing et d'analyse web.<\/p>\n<h4>3.3.4 Mise \u00e0 disposition prescrite ou n\u00e9cessaire :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Bien entendu, vous pouvez en principe consulter notre site web sans cookies. Les navigateurs web sont r\u00e9guli\u00e8rement configur\u00e9s pour accepter les cookies. En g\u00e9n\u00e9ral, vous pouvez \u00e0 tout moment d\u00e9sactiver l'utilisation de cookies en modifiant les param\u00e8tres de votre navigateur (voir R\u00e9vocation du consentement).<\/p>\n<p>Veuillez noter que certaines fonctions de notre site web peuvent ne pas fonctionner si vous avez d\u00e9sactiv\u00e9 l'utilisation de cookies.<\/p>\n<h4>3.3.5 R\u00e9vocation du consentement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Vous pouvez r\u00e9voquer votre consentement \u00e0 tout moment via notre outil de consentement aux cookies. <\/p>\n<h4>3.3.6 Profilage :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Pour savoir dans quelle mesure nous analysons le comportement des visiteurs du site web \u00e0 l'aide de profils d'utilisateurs pseudonymis\u00e9s, veuillez consulter les informations ci-dessous sur les technologies de pr\u00e9sentation, de suivi, de remarketing et d'analyse web utilis\u00e9es.<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>4\u00e8me bulletin d'information<\/h3>\n<h4>4.1 Nature et finalit\u00e9 du traitement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Pour l'envoi de notre newsletter, nous collectons des donn\u00e9es personnelles qui nous sont transmises via un masque de saisie.<\/p>\n<p>Pour que l'inscription soit valable, nous avons besoin d'une adresse e-mail valide. Afin de v\u00e9rifier que l'inscription est effectivement effectu\u00e9e par le propri\u00e9taire d'une adresse e-mail, nous utilisons la proc\u00e9dure de \"double opt-in\". Pour ce faire, nous enregistrons l'inscription \u00e0 la newsletter, l'envoi d'un e-mail de confirmation et la r\u00e9ception de la r\u00e9ponse ainsi demand\u00e9e. Aucune autre donn\u00e9e n'est collect\u00e9e. <\/p>\n<h4>4.2 Base juridique :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Sur la base de votre consentement explicite (article 6, paragraphe 1, point a) du RGPD), nous vous envoyons r\u00e9guli\u00e8rement notre newsletter ou des informations comparables par e-mail \u00e0 l'adresse \u00e9lectronique que vous avez indiqu\u00e9e. <\/p>\n<p>Vous pouvez \u00e0 tout moment r\u00e9voquer votre consentement \u00e0 l'enregistrement de vos donn\u00e9es personnelles et \u00e0 leur utilisation pour l'envoi de la newsletter, avec effet pour l'avenir. Un lien \u00e0 cet effet se trouve dans chaque newsletter. En outre, vous pouvez \u00e9galement vous d\u00e9sinscrire \u00e0 tout moment directement sur ce site web ou nous communiquer votre r\u00e9vocation via l'option de contact indiqu\u00e9e \u00e0 la fin des pr\u00e9sentes informations sur la protection des donn\u00e9es.<\/p>\n<h4>4.3 Destinataires :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les destinataires des donn\u00e9es sont, le cas \u00e9ch\u00e9ant, des sous-traitants.<\/p>\n<p><\/p><h4>4.4 Transfert vers un pays tiers :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les donn\u00e9es collect\u00e9es peuvent \u00eatre transf\u00e9r\u00e9es vers les pays tiers suivants : aucun. <\/p>\n<p>Les garanties de protection des donn\u00e9es suivantes sont disponibles : <\/p>\n<p><\/p><h4>4.5 Dur\u00e9e de conservation :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Dans ce contexte, les donn\u00e9es ne sont trait\u00e9es que tant que le consentement correspondant est donn\u00e9. Elles seront ensuite supprim\u00e9es.<\/p>\n<h4>4.6 Mise \u00e0 disposition prescrite ou n\u00e9cessaire :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>La mise \u00e0 disposition de vos donn\u00e9es personnelles est volontaire, uniquement sur la base de votre consentement. Sans votre consentement, nous ne pouvons malheureusement pas vous envoyer notre newsletter.<\/p>\n<h4>4.7 R\u00e9vocation du consentement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Vous pouvez \u00e0 tout moment r\u00e9voquer votre consentement \u00e0 l'enregistrement de vos donn\u00e9es personnelles et \u00e0 leur utilisation pour l'envoi de la newsletter, avec effet pour l'avenir. La d\u00e9sinscription peut \u00eatre demand\u00e9e via le lien contenu dans chaque e-mail ou aupr\u00e8s du d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es ou de la personne responsable de la protection des donn\u00e9es mentionn\u00e9e ci-dessous. <\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>5. formulaire de contact<\/h3>\n<h4>5.1 Nature et finalit\u00e9 du traitement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les donn\u00e9es que vous avez saisies sont enregistr\u00e9es dans le but de communiquer individuellement avec vous. Pour cela, il est n\u00e9cessaire d'indiquer une adresse e-mail valide ainsi que votre nom. Celle-ci sert \u00e0 l'attribution de la demande et \u00e0 la r\u00e9ponse ult\u00e9rieure \u00e0 celle-ci. L'indication d'autres donn\u00e9es est facultative.<\/p>\n<h4>5.2 Base juridique :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Le traitement des donn\u00e9es saisies dans le formulaire de contact se fonde sur un int\u00e9r\u00eat l\u00e9gitime (article 6, paragraphe 1, point f du RGPD).<\/p>\n<p>En mettant \u00e0 disposition le formulaire de contact, nous souhaitons vous permettre de nous contacter facilement. Vos donn\u00e9es sont enregistr\u00e9es dans le but de traiter votre demande et de r\u00e9pondre \u00e0 d'\u00e9ventuelles questions.<\/p>\n<p>Si vous nous contactez pour demander une offre, le traitement des donn\u00e9es saisies dans le formulaire de contact a lieu pour l'ex\u00e9cution de mesures pr\u00e9contractuelles (article 6, paragraphe 1, point b) du RGPD).<\/p>\n<h4>5.3 Destinataires :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les destinataires des donn\u00e9es sont, le cas \u00e9ch\u00e9ant, des sous-traitants.<\/p>\n<p><\/p><h4>5.4 Transfert vers un pays tiers :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les donn\u00e9es collect\u00e9es peuvent \u00eatre transf\u00e9r\u00e9es vers les pays tiers suivants : aucun.<\/p>\n<p>Les garanties de protection des donn\u00e9es suivantes sont disponibles : <\/p>\n<p><\/p><h4>5.5 Dur\u00e9e de conservation :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Les donn\u00e9es sont effac\u00e9es au plus tard 6 mois apr\u00e8s le traitement de la demande.<\/p>\n<p>Dans la mesure o\u00f9 il y a une relation contractuelle, nous sommes soumis aux d\u00e9lais de conservation l\u00e9gaux selon le code de commerce allemand et nous supprimons vos donn\u00e9es apr\u00e8s l'expiration de ces d\u00e9lais. <\/p>\n<h4>5.6 Mise \u00e0 disposition prescrite ou n\u00e9cessaire :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>La fourniture de vos donn\u00e9es personnelles est volontaire. Nous ne pouvons toutefois traiter votre demande que si vous nous communiquez votre nom, votre adresse e-mail et le motif de votre demande.<\/p>\n<br><br><hr>\n<br><br>\n<h3>6. reCAPTCHA<\/h3>\n<p>reCAPTCHA (fournisseur : Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA). a pour but de v\u00e9rifier si la saisie de donn\u00e9es sur nos sites Web (par ex. dans le formulaire de d\u00e9monstration) est effectu\u00e9e par un \u00eatre humain ou par un programme automatis\u00e9. Pour ce faire, reCAPTCHA analyse le comportement du visiteur du site Web \u00e0 l'aide de diff\u00e9rentes caract\u00e9ristiques. Cette analyse commence automatiquement d\u00e8s que le visiteur du site web entre sur le site. Pour l'analyse, reCAPTCHA \u00e9value diff\u00e9rentes informations (par exemple l'adresse IP, le temps pass\u00e9 par le visiteur du site sur le site ou les mouvements de souris effectu\u00e9s par l'utilisateur). Les donn\u00e9es collect\u00e9es lors de l'analyse sont transmises \u00e0 Google.\n\nLe traitement des donn\u00e9es s'effectue sur la base de l'article 6, paragraphe 1, point f du RGPD. Nous avons un int\u00e9r\u00eat l\u00e9gitime \u00e0 prot\u00e9ger nos offres web contre les requ\u00eates automatis\u00e9es abusives.\n\nPour plus d'informations sur Google reCAPTCHA et la d\u00e9claration de confidentialit\u00e9 de Google, veuillez consulter les liens suivants : https:\/\/www.google.com\/intl\/de\/policies\/privacy\/ et https:\/\/www.google.com\/recaptcha\/intro\/android.html.<\/p>\n<br><br><hr>\n<br><br>\n<h3>7. utilisation de Pipedrive<\/h3>\n<p>Nous utilisons Pipedrive sur notre site web, une plateforme CRM pour la vente. Le fournisseur de services est l'entreprise am\u00e9ricaine Pipedrive Inc, 460 Park Ave South, New York, NY, 10016, USA.<\/p><p>Pipedrive traite vos donn\u00e9es, entre autres, aux \u00c9tats-Unis. Nous attirons votre attention sur le fait que, selon la Cour de justice europ\u00e9enne, il n'existe actuellement pas de niveau de protection ad\u00e9quat pour le transfert de donn\u00e9es vers les \u00c9tats-Unis. Cela peut s'accompagner de diff\u00e9rents risques pour la l\u00e9galit\u00e9 et la s\u00e9curit\u00e9 du traitement des donn\u00e9es.<\/p><p>Pipedrive utilise des clauses contractuelles standard (= article 46, paragraphes 2 et 3 du RGPD) comme base de traitement des donn\u00e9es pour les destinataires situ\u00e9s dans des pays tiers (en dehors de l'Union europ\u00e9enne, de l'Islande, du Liechtenstein, de la Norv\u00e8ge, donc en particulier aux \u00c9tats-Unis) ou pour la transmission de donn\u00e9es vers ces pays. Les clauses contractuelles standard (CCS) sont des mod\u00e8les mis \u00e0 disposition par la Commission europ\u00e9enne et visent \u00e0 garantir que vos donn\u00e9es sont conformes aux normes europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es, m\u00eame si elles sont transf\u00e9r\u00e9es et stock\u00e9es dans des pays tiers (comme les \u00c9tats-Unis). Par ces clauses, Pipedrive s'engage \u00e0 respecter le niveau europ\u00e9en de protection des donn\u00e9es lors du traitement de vos donn\u00e9es pertinentes, m\u00eame si ces donn\u00e9es sont stock\u00e9es, trait\u00e9es et g\u00e9r\u00e9es aux \u00c9tats-Unis. Ces clauses sont bas\u00e9es sur une d\u00e9cision d'ex\u00e9cution de la Commission europ\u00e9enne. Vous trouverez la d\u00e9cision et les clauses contractuelles types correspondantes ici, entre autres : <a href=\"https:\/\/eur-lex.europa.eu\/eli\/dec_impl\/2021\/914\/oj?locale=de\" target=\"_blank\" rel=\"noopener\">https:\/\/eur-lex.europa.eu\/eli\/dec_impl\/2021\/914\/oj?locale=de<\/a><\/p><p>La condition de traitement des donn\u00e9es (Data Protection Addendum) de Pipedrive, qui correspond aux clauses contractuelles standard, est disponible \u00e0 l'adresse suivante <a href=\"https:\/\/www-cms.pipedriveassets.com\/documents\/2021-02-16-Pipedrive-DPA-Signed.pdf\">https:\/\/www-cms.pipedriveassets.com\/documents\/2021-02-16-Pipedrive-DPA-Signed.pdf<\/a>.<\/p><p>Pour en savoir plus sur les donn\u00e9es trait\u00e9es par l'utilisation de Pipedrive, consultez la Privacy Policy sur <a href=\"https:\/\/www.pipedrive.com\/en\/privacy\" target=\"_blank\" rel=\"noopener\">https:\/\/www.pipedrive.com\/en\/privacy<\/a>.<\/p><p><\/p><p style=\"margin-top:15px;\">\n\nSource : Cr\u00e9\u00e9 avec le <a href=\"https:\/\/www.adsimple.de\/datenschutz-generator\/\">G\u00e9n\u00e9rateur de protection des donn\u00e9es<\/a> de AdSimple<\/p><br><br><hr><span style=\"background-color: #ebff24; user-select: auto;\"><\/span><p><\/p>\n<br><br>\n<h3>8. utilisation de Calendly<\/h3>\n<p>Nous offrons la possibilit\u00e9 de r\u00e9server un rendez-vous t\u00e9l\u00e9phonique (\u00e9galement appel\u00e9 \"premier entretien, appel t\u00e9l\u00e9phonique strat\u00e9gique\").  Pour la r\u00e9servation et la gestion d'un rendez-vous t\u00e9l\u00e9phonique, nous utilisons le logiciel \"Calendly\". \"Calendly\" est un service de Calendly, LLC, 3423 Piedmont Road NE, Atlanta, GA 30305-1754, United States.\n\nSi vous remplissez le formulaire avec vos coordonn\u00e9es, choisissez un rendez-vous disponible et appuyez sur le bouton correspondant, vous recevrez automatiquement un e-mail de Calendly confirmant votre rendez-vous.\n\nVos donn\u00e9es du formulaire Calendly, y compris les donn\u00e9es que vous y avez indiqu\u00e9es, sont enregistr\u00e9es chez nous et Calendly pour le traitement de la demande et en cas de questions de suivi. Ces donn\u00e9es y resteront jusqu'\u00e0 ce que vous nous demandiez de les effacer, que vous r\u00e9voquiez votre consentement \u00e0 leur enregistrement ou que le but de leur enregistrement ne soit plus valable (par ex. un rendez-vous a \u00e9t\u00e9 fix\u00e9). Les dispositions l\u00e9gales contraignantes - en particulier les d\u00e9lais de conservation - ne sont pas affect\u00e9es.\n\nNous avons conclu un \"Data Processing Addendum\" avec Calendly. Il s'agit d'un contrat par lequel Calendly s'engage \u00e0 prot\u00e9ger les donn\u00e9es de nos utilisateurs, \u00e0 les traiter en mon nom conform\u00e9ment \u00e0 ses dispositions en mati\u00e8re de protection des donn\u00e9es et, en particulier, \u00e0 ne pas les transmettre \u00e0 des tiers. Pour plus d'informations sur Calendly et la protection des donn\u00e9es chez Calendly, veuillez consulter : https:\/\/calendly.com\/pages\/privacy .<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>9. utilisation de Google Analytics<\/h3>\n<p>Dans la mesure o\u00f9 vous avez donn\u00e9 votre accord, ce site web utilise Google Analytics, un service d'analyse web de Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043 USA (ci-apr\u00e8s : \"Google\"). Google Analytics utilise des \"cookies\", c'est-\u00e0-dire des fichiers texte qui sont enregistr\u00e9s sur votre ordinateur et qui permettent d'analyser votre utilisation du site web. Les informations g\u00e9n\u00e9r\u00e9es par le cookie concernant votre utilisation de ce site web sont g\u00e9n\u00e9ralement transmises \u00e0 un serveur de Google aux \u00c9tats-Unis et y sont enregistr\u00e9es. En raison de l'activation de l'anonymisation IP sur ces pages web, votre adresse IP sera toutefois abr\u00e9g\u00e9e par Google au sein des \u00c9tats membres de l'Union europ\u00e9enne ou dans d'autres \u00c9tats signataires de l'accord sur l'Espace \u00e9conomique europ\u00e9en. Ce n'est que dans des cas exceptionnels que l'adresse IP compl\u00e8te est transmise \u00e0 un serveur de Google aux \u00c9tats-Unis et y est abr\u00e9g\u00e9e. L'adresse IP transmise par votre navigateur dans le cadre de Google Analytics n'est pas recoup\u00e9e avec d'autres donn\u00e9es de Google. <\/p>\n<p>Pour plus d'informations sur les conditions d'utilisation et la protection des donn\u00e9es, voir <a href=\"https:\/\/www.google.com\/analytics\/terms\/de.html et sur https:\/\/policies.google.com\/?hl=de\" rel=\"noopener\" target=\"_blank\">https:\/\/www.google.com\/analytics\/terms\/de.html et sur https:\/\/policies.google.com\/?hl=de<\/a>. <\/p>\n<p>Google utilisera ces informations pour le compte de l'exploitant de ce site web afin d'\u00e9valuer votre utilisation du site web, de compiler des rapports sur les activit\u00e9s du site web et de fournir \u00e0 l'exploitant du site web d'autres services li\u00e9s \u00e0 l'utilisation du site web et d'Internet. <\/p>\n<p>Les donn\u00e9es que nous envoyons et qui sont li\u00e9es \u00e0 des cookies, \u00e0 des identifiants d'utilisateur (par ex. ID utilisateur) ou \u00e0 des ID publicitaires sont automatiquement supprim\u00e9es apr\u00e8s 14 mois. Les donn\u00e9es dont la dur\u00e9e de conservation est atteinte sont automatiquement supprim\u00e9es une fois par mois.<\/p>\n<h4>9.1 R\u00e9vocation du consentement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>L'adresse IP transmise par le navigateur de l'utilisateur ne sera pas recoup\u00e9e avec d'autres donn\u00e9es de Google. Vous pouvez en outre emp\u00eacher la saisie par Google des donn\u00e9es g\u00e9n\u00e9r\u00e9es par le cookie et relatives \u00e0 votre utilisation du site web (y compris votre adresse IP) ainsi que le traitement de ces donn\u00e9es par Google en t\u00e9l\u00e9chargeant et en installant le plug-in de navigateur disponible sous le lien suivant : <a href=\"http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" rel=\"noopener\" target=\"_blank\">Module compl\u00e9mentaire de navigateur pour la d\u00e9sactivation de Google Analytics<\/a>.<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>10. utilisation de Google Maps<\/h3>\n<p>Sur ce site web, nous utilisons l'offre de Google Maps. Google Maps est exploit\u00e9 par Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA (ci-apr\u00e8s \"Google\"). Cela nous permet d'afficher des cartes interactives directement sur le site web et vous permet d'utiliser confortablement la fonction de carte.<br>Pour plus d'informations sur le traitement des donn\u00e9es par Google, veuillez consulter les informations sur la protection des donn\u00e9es de Google : <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"noopener nofollow\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a>. Vous pouvez \u00e9galement y modifier vos param\u00e8tres personnels de protection des donn\u00e9es dans le centre de protection des donn\u00e9es.<\/p>\n<p>Vous trouverez ici des instructions d\u00e9taill\u00e9es sur la gestion de vos propres donn\u00e9es en relation avec les produits Google : <a href=\"https:\/\/www.dataliberation.org\/\" rel=\"noopener nofollow\" target=\"_blank\">https:\/\/www.dataliberation.org<\/a><\/p>\n<p>Lors de la visite du site web, Google re\u00e7oit des informations indiquant que vous avez consult\u00e9 la sous-page correspondante de notre site web. Cela se produit ind\u00e9pendamment du fait que Google mette \u00e0 disposition un compte d'utilisateur par lequel vous \u00eates connect\u00e9 ou qu'il n'existe pas de compte d'utilisateur. Si vous \u00eates connect\u00e9 \u00e0 Google, vos donn\u00e9es seront directement attribu\u00e9es \u00e0 votre compte. <\/p>\n<p>Si vous ne souhaitez pas que votre profil soit associ\u00e9 \u00e0 Google, vous devez vous d\u00e9connecter de Google avant d'activer le bouton. Google enregistre vos donn\u00e9es en tant que profils d'utilisation et les utilise \u00e0 des fins de publicit\u00e9, d'\u00e9tude de march\u00e9 et\/ou de conception de ses sites web en fonction des besoins. Une telle \u00e9valuation a lieu en particulier (m\u00eame pour les utilisateurs non connect\u00e9s) pour fournir une publicit\u00e9 adapt\u00e9e aux besoins et pour informer d'autres utilisateurs du r\u00e9seau social de vos activit\u00e9s sur notre site web. Vous disposez d'un droit d'opposition \u00e0 la cr\u00e9ation de ces profils d'utilisateurs, que vous devez exercer en vous adressant \u00e0 Google. <\/p>\n<h4>10.1 R\u00e9vocation du consentement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Le fournisseur n'offre actuellement aucune possibilit\u00e9 de simple opt-out ou de blocage de la transmission de donn\u00e9es. Si vous souhaitez emp\u00eacher le suivi de vos activit\u00e9s sur notre site web, veuillez r\u00e9voquer votre consentement dans l'outil de consentement aux cookies pour la cat\u00e9gorie de cookies correspondante ou pour tous les cookies et transferts de donn\u00e9es qui ne sont pas n\u00e9cessaires d'un point de vue technique. Dans ce cas, il se peut toutefois que vous ne puissiez pas utiliser notre site web ou seulement de mani\u00e8re limit\u00e9e.<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>11. vid\u00e9os YouTube int\u00e9gr\u00e9es<\/h3>\n<p>Sur notre site web, nous int\u00e9grons des vid\u00e9os YouTube. L'exploitant des plugins correspondants est YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA (ci-apr\u00e8s \"YouTube\"). YouTube, LLC est une filiale de Google LLC, 1600 Amphitheatre Pkwy, Mountain View, CA 94043, USA (ci-apr\u00e8s \"Google\"). Lorsque vous visitez une page avec le plug-in YouTube, une connexion est \u00e9tablie avec les serveurs de YouTube. YouTube est alors inform\u00e9 des pages que vous visitez. Si vous \u00eates connect\u00e9 \u00e0 votre compte YouTube, YouTube peut vous attribuer personnellement votre comportement de navigation. Vous pouvez \u00e9viter cela en vous d\u00e9connectant au pr\u00e9alable de votre compte YouTube. <\/p>\n<p>Lorsqu'une vid\u00e9o YouTube est lanc\u00e9e, le fournisseur utilise des cookies qui collectent des informations sur le comportement de l'utilisateur. <\/p>\n<p>Pour plus d'informations sur l'objectif et l'\u00e9tendue de la collecte de donn\u00e9es et de leur traitement par YouTube, veuillez consulter la d\u00e9claration de confidentialit\u00e9 du fournisseur. Vous y trouverez \u00e9galement de plus amples informations sur vos droits en la mati\u00e8re et les possibilit\u00e9s de param\u00e9trage pour prot\u00e9ger votre vie priv\u00e9e (<a href=\"https:\/\/policies.google.com\/privacy\">https:\/\/policies.google.com\/privacy<\/a>). <\/p>\n<h4>11.1 R\u00e9vocation du consentement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Le fournisseur n'offre actuellement aucune possibilit\u00e9 de simple opt-out ou de blocage de la transmission de donn\u00e9es. Si vous souhaitez emp\u00eacher le suivi de vos activit\u00e9s sur notre site web, veuillez r\u00e9voquer votre consentement dans l'outil de consentement aux cookies pour la cat\u00e9gorie de cookies correspondante ou pour tous les cookies et transferts de donn\u00e9es qui ne sont pas n\u00e9cessaires d'un point de vue technique. Dans ce cas, il se peut toutefois que vous ne puissiez pas utiliser notre site web ou seulement de mani\u00e8re limit\u00e9e.<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>12. Google AdWords<\/h3>\n<p>Notre site Internet utilise le suivi des conversions de Google. La soci\u00e9t\u00e9 exploitant les services de Google AdWords est Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA. Si vous avez acc\u00e9d\u00e9 \u00e0 notre site web par le biais d'une annonce publi\u00e9e par Google, Google Adwords place un cookie sur votre ordinateur. Le cookie de suivi des conversions est install\u00e9 lorsqu'un utilisateur clique sur une annonce diffus\u00e9e par Google.<\/p>\n<p>Si l'utilisateur visite certaines pages de notre site web et que le cookie n'a pas encore expir\u00e9, Google et nous-m\u00eames pouvons reconna\u00eetre que l'utilisateur a cliqu\u00e9 sur l'annonce et a \u00e9t\u00e9 redirig\u00e9 vers cette page. Chaque client Google AdWords re\u00e7oit un cookie diff\u00e9rent. Les cookies ne peuvent donc pas \u00eatre suivis via les sites web des clients AdWords. Les informations obtenues \u00e0 l'aide du cookie de conversion servent \u00e0 \u00e9tablir des statistiques de conversion pour les clients AdWords qui ont opt\u00e9 pour le suivi des conversions. Les clients apprennent le nombre total d'utilisateurs qui ont cliqu\u00e9 sur leur annonce et ont \u00e9t\u00e9 redirig\u00e9s vers une page dot\u00e9e d'une balise de suivi des conversions. Ils ne re\u00e7oivent toutefois aucune information permettant d'identifier personnellement les utilisateurs.<\/p>\n<p>Pour plus d'informations sur le traitement des donn\u00e9es par Google, veuillez consulter les informations sur la protection des donn\u00e9es de Google : <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"noopener nofollow\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a>. Vous pouvez \u00e9galement y modifier vos param\u00e8tres personnels de protection des donn\u00e9es dans le centre de protection des donn\u00e9es.<\/p>\n<h4>12.1 R\u00e9vocation du consentement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Le fournisseur n'offre actuellement aucune possibilit\u00e9 de simple opt-out ou de blocage de la transmission de donn\u00e9es. Si vous souhaitez emp\u00eacher le suivi de vos activit\u00e9s sur notre site web, veuillez r\u00e9voquer votre consentement dans l'outil de consentement aux cookies pour la cat\u00e9gorie de cookies correspondante ou pour tous les cookies et transferts de donn\u00e9es qui ne sont pas n\u00e9cessaires d'un point de vue technique. Dans ce cas, il se peut toutefois que vous ne puissiez pas utiliser notre site web ou seulement de mani\u00e8re limit\u00e9e.<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>13. utilisation de Google Remarketing<\/h3>\n<p>Ce site utilise la fonction de remarketing de Google Inc. La soci\u00e9t\u00e9 d'exploitation des services de Google Remarketing est Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA (ci-apr\u00e8s \"Google\").<\/p>\n<p>Cette fonction sert \u00e0 pr\u00e9senter aux visiteurs du site web des annonces publicitaires cibl\u00e9es par centres d'int\u00e9r\u00eat au sein du r\u00e9seau publicitaire de Google. Un \"cookie\" est enregistr\u00e9 dans le navigateur du visiteur du site web, ce qui permet de reconna\u00eetre le visiteur lorsqu'il consulte des pages web qui font partie du r\u00e9seau publicitaire de Google. Sur ces pages, des annonces publicitaires peuvent \u00eatre pr\u00e9sent\u00e9es au visiteur, qui se rapportent \u00e0 des contenus que le visiteur a consult\u00e9s auparavant sur des pages web qui utilisent la fonction de remarketing de Google.<\/p>\n<p>Pour plus d'informations sur le traitement des donn\u00e9es par Google, veuillez consulter les informations sur la protection des donn\u00e9es de Google : <a href=\"https:\/\/policies.google.com\/privacy\" rel=\"noopener nofollow\" target=\"_blank\">https:\/\/policies.google.com\/privacy<\/a>. Vous pouvez \u00e9galement y modifier vos param\u00e8tres personnels de protection des donn\u00e9es dans le centre de protection des donn\u00e9es. <\/p>\n<h4>13.1 R\u00e9vocation du consentement :<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Le fournisseur n'offre actuellement aucune possibilit\u00e9 de simple opt-out ou de blocage de la transmission de donn\u00e9es. Si vous souhaitez emp\u00eacher le suivi de vos activit\u00e9s sur notre site web, veuillez r\u00e9voquer votre consentement dans l'outil de consentement aux cookies pour la cat\u00e9gorie de cookies correspondante ou pour tous les cookies et transferts de donn\u00e9es qui ne sont pas n\u00e9cessaires d'un point de vue technique. Dans ce cas, il se peut toutefois que vous ne puissiez pas utiliser notre site web ou seulement de mani\u00e8re limit\u00e9e.<\/p>\n<br><br><hr>\n<br><br>\n<p><\/p><h3>14. cryptage SSL<\/h3>\n<p>Afin de prot\u00e9ger la s\u00e9curit\u00e9 de vos donn\u00e9es lors de leur transmission, nous utilisons des proc\u00e9dures de cryptage conformes \u00e0 l'\u00e9tat actuel de la technique (par ex. SSL) via HTTPS.<\/p>\n<p><\/p>\n<br><br><hr>\n<br><br>\n<h3>15. transfert de pays tiers<\/h3>\n<p>\nDans le cadre de l'utilisation des outils de Google, nous transmettons entre autres votre adresse IP abr\u00e9g\u00e9e aux \u00c9tats-Unis. Par ailleurs, un transfert de donn\u00e9es en dehors de l'UE\/EEE peut \u00e9galement avoir lieu dans le cadre de l'utilisation des outils de Microsoft, LinkedIn, Hotjar ainsi que Facebook.\n\nSi des prestataires de services sont utilis\u00e9s en dehors de l'UE\/EEE et qu'il n'existe pas de \"d\u00e9cision d'ad\u00e9quation\" de la Commission europ\u00e9enne pour ce pays, ces prestataires de services sont tenus, en plus des instructions \u00e9crites, de respecter le niveau de protection des donn\u00e9es en Europe par le biais de l'accord sur les clauses contractuelles types de l'UE. Malheureusement, en raison des lois de pays non membres de l'UE (par exemple dans le cadre du \"Cloud Act\" aux \u00c9tats-Unis), il est toutefois possible, m\u00eame en cas de conclusion d'accords et de r\u00e8glements correspondants, que des services publics en particulier aient acc\u00e8s \u00e0 vos donn\u00e9es personnelles sans que nous ou vous ne puissions le savoir ou l'emp\u00eacher, l'emp\u00eacher ou le contr\u00f4ler. Pour ces raisons, votre consentement, par exemple \u00e0 l'utilisation de cookies (par exemple pour Google Analytics), inclut \u00e9galement la finalit\u00e9 du transfert de donn\u00e9es en dehors de l'UE. Pour plus d'informations, veuillez contacter notre responsable de la protection des donn\u00e9es.\n\nPar ailleurs, nous ne transf\u00e9rons pas vos donn\u00e9es personnelles en dehors de l'UE ou de l'EEE, ni \u00e0 des organisations internationales.<\/p>\n\n\n<br><br><hr>\n<br><br>\n<h3>16. information sur votre droit d'opposition conform\u00e9ment \u00e0 l'article 21 du RGPD<\/h3>\n<h4>16.1 Droit d'opposition au cas par cas<\/h4>\n<p style=\"margin-bottom: -25px;\"><\/p>\n<p>Vous avez le droit de vous opposer \u00e0 tout moment, pour des raisons tenant \u00e0 votre situation particuli\u00e8re, au traitement des donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant effectu\u00e9 sur la base de l'article 6, paragraphe 1, point f), du RGPD (traitement des donn\u00e9es sur la base d'une mise en balance des int\u00e9r\u00eats) ; cela vaut \u00e9galement pour le profilage fond\u00e9 sur cette disposition au sens de l'article 4, point 4, du RGPD.<\/p>\n<p>Si vous vous y opposez, nous ne traiterons plus vos donn\u00e9es \u00e0 caract\u00e8re personnel, \u00e0 moins que nous puissions d\u00e9montrer qu'il existe des motifs l\u00e9gitimes et imp\u00e9rieux pour le traitement qui pr\u00e9valent sur vos int\u00e9r\u00eats, vos droits et vos libert\u00e9s, ou que le traitement sert \u00e0 faire valoir, \u00e0 exercer ou \u00e0 d\u00e9fendre des droits en justice.<\/p>\n<h4>Destinataire d'une opposition<\/h4>\n<p style=\"margin-bottom: -35px;\"><\/p>\n<p>datenschutz@locaterisk.com<\/p>\n<br><br><hr>\n<br><br>\n<h3>17. vos droits en tant que personne concern\u00e9e<\/h3>\n<p>Vous pouvez \u00e0 tout moment exercer les droits suivants en utilisant les coordonn\u00e9es indiqu\u00e9es de notre responsable de la protection des donn\u00e9es :\n<ul>\n<ul style=\"list-style-type: disc;margin-left:20px;font-size: 1.6em; line-height: 130%\">\n<li>Information sur vos donn\u00e9es enregistr\u00e9es chez nous et sur leur traitement (art. 15 RGPD),\n,<\/li>\n<li>Rectification des donn\u00e9es \u00e0 caract\u00e8re personnel inexactes (article 16 du RGPD),<\/li>\n<li>Suppression de vos donn\u00e9es enregistr\u00e9es chez nous (art. 17 RGPD),<\/li>\n<li>la limitation du traitement des donn\u00e9es, dans la mesure o\u00f9 nous ne sommes pas encore autoris\u00e9s \u00e0 supprimer vos donn\u00e9es en raison d'obligations l\u00e9gales (article 18 du RGPD),<\/li>\n<li>opposition au traitement de vos donn\u00e9es par nos soins (art. 21 RGPD) et<\/li>\n<li>la portabilit\u00e9 des donn\u00e9es, dans la mesure o\u00f9 vous avez consenti au traitement des donn\u00e9es ou conclu un contrat avec nous (article 20 du RGPD).<\/li>\n<\/ul>\n<p>Si vous nous avez donn\u00e9 votre consentement, vous pouvez le r\u00e9voquer \u00e0 tout moment avec effet pour l'avenir.<\/p>\n<p>Vous pouvez \u00e0 tout moment d\u00e9poser une plainte aupr\u00e8s d'une autorit\u00e9 de surveillance, par exemple aupr\u00e8s de l'autorit\u00e9 de surveillance comp\u00e9tente du Land de votre domicile ou aupr\u00e8s de l'autorit\u00e9 comp\u00e9tente pour nous en tant qu'organisme responsable.<\/p>\n<p>Vous trouverez une liste des autorit\u00e9s de contr\u00f4le (pour le secteur non public) avec leur adresse sur le site : <a href=\"https:\/\/www.bfdi.bund.de\/DE\/Service\/Anschriften\/Laender\/Laender-node.html\" target=\"_blank\" rel=\"noopener nofollow\">https:\/\/www.bfdi.bund.de\/DE\/Service\/Anschriften\/Laender\/Laender-node.html<\/a>.<\/p>\n\n<br><br><hr>\n<br><br>\n<h3>18. modification de notre politique de confidentialit\u00e9<\/h3>\n<p>Nous nous r\u00e9servons le droit d'adapter la pr\u00e9sente d\u00e9claration de protection des donn\u00e9es afin qu'elle soit toujours conforme aux exigences l\u00e9gales actuelles ou afin de mettre en \u0153uvre les modifications de nos prestations dans la d\u00e9claration de protection des donn\u00e9es, par exemple lors de l'introduction de nouveaux services. La nouvelle d\u00e9claration de protection des donn\u00e9es s'appliquera alors \u00e0 votre nouvelle visite.<\/p>\n<br><br><hr>\n<br><br>\n<h3>19. questions au d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es<\/h3>\n<p>Si vous avez des questions concernant la protection des donn\u00e9es, veuillez nous envoyer un e-mail ou vous adresser directement \u00e0 la personne responsable de la protection des donn\u00e9es dans notre organisation :<\/p>\n<p>datenschutz@locaterisk.com<\/p>\n<p><em>La d\u00e9claration de protection des donn\u00e9es a \u00e9t\u00e9 r\u00e9dig\u00e9e avec l'aide d'activeMind AG, les experts en mati\u00e8re de protection des donn\u00e9es. <a href=\"https:\/\/www.activemind.de\/datenschutz\/datenschutzbeauftragter\/\" target=\"_blank\" rel=\"noopener\">d\u00e9l\u00e9gu\u00e9s \u00e0 la protection des donn\u00e9es externes<\/a> (version #2020-09-30).<\/em><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-lr-contact-module\"><div class=\"content\"><h2>En savoir plus, r\u00e9server une d\u00e9mo ou simplement \u00e9changer quelques mots ? Nous nous en r\u00e9jouissons !<\/h2><div class=\"contact-info-row\"><div class=\"contact-person-info\"><div class=\"avatar\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2025\/06\/Lukas_Baumann_LocateRisk-300.png\"><\/div><p><span class=\"text before\">Votre Contact<\/span><span class=\"bold name\"><strong>Lukas<\/strong><\/span> <span class=\"lastname\"><strong>Baumann<strong><\/strong><\/strong><\/span><strong><strong><span class=\"separator\"><\/span><span class=\"role\">PDG<\/span><\/strong><\/strong><\/p><\/div><p class=\"bold phone\"><strong><strong>+49 6151 6290246<\/strong><\/strong><\/p><strong><strong><a class=\"pr-1\" href=\"mailto: sales@locaterisk.com\">Contactez-nous maintenant<\/a><\/strong><\/strong><\/div><\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-lr-footer-module lr-footer-block\"><div class=\"content\"><div class=\"column0\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/assets\/img\/lr-logo.svg\"\/><\/div><div class=\"categories\"><div class=\"categories-element\"><a class=\"pr-4\" href=\"https:\/\/locaterisk.com\/fr\/\">Accueil<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/blog\/\">Blog<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/about\/\">par rapport \u00e0 nous<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/kontakt\/\">Contact<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/impressum\/\">mentiones l\u00e9gales<\/a><\/div><div class=\"categories-break\"><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/datenschutz\/\">Confidentialit\u00e9<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/files\/agb.pdf\">CONDITIONS G\u00c9N\u00c9RALES DE VENTE<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/jobs\/\">Carri\u00e8re<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/files\/sec-information.pdf\">s\u00e9curit\u00e9<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"https:\/\/app.secfix.com\/trust\/locaterisk\/d1e7d433b33643aea1880bfbfeab9f60\">Centre de confiance<\/a><\/div><\/div><div class=\"social\"><div class=\"social-element\"><a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/company\/locaterisk\/\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/10\/gruppe-230@3x.png\"\/><\/a><\/div><div class=\"social-element\"><a target=\"_blank\" href=\"https:\/\/www.instagram.com\/locaterisk\/\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Instagram.png\"\/><\/a><\/div><div class=\"social-element\"><a target=\"_blank\" href=\"https:\/\/twitter.com\/locaterisk\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/twitter.png\"\/><\/a><\/div><\/div><div class=\"description\"><h6>\u00a9 LocateRisk 2026<\/h6><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Wir freuen uns, dass Sie unsere Website besuchen. Uns ist der Schutz Ihrer Privatsph\u00e4re sehr wichtig und wir m\u00f6chten, dass Sie sich bei der Nutzung der Seiten sicher f\u00fchlen. Aus diesem Grund behandeln wir Ihre Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung. 1. Name und Anschrift des Verantwortlichen Verantwortlicher im Sinne [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-840","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz - LocateRisk<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/locaterisk.com\/fr\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - LocateRisk\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung Wir freuen uns, dass Sie unsere Website besuchen. Uns ist der Schutz Ihrer Privatsph\u00e4re sehr wichtig und wir m\u00f6chten, dass Sie sich bei der Nutzung der Seiten sicher f\u00fchlen. Aus diesem Grund behandeln wir Ihre Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung. 1. Name und Anschrift des Verantwortlichen Verantwortlicher im Sinne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/locaterisk.com\/fr\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"LocateRisk\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-14T16:14:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Kettenglieder_Generisch_03-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/datenschutz\\\/\",\"name\":\"Datenschutz - LocateRisk\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#website\"},\"datePublished\":\"2020-11-04T10:53:54+00:00\",\"dateModified\":\"2022-07-14T16:14:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/datenschutz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/locaterisk.com\\\/datenschutz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/datenschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/locaterisk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/\",\"name\":\"LocateRisk\",\"description\":\"IT-Sicherheit messen und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#organization\",\"name\":\"LocateRisk\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Kettenglieder_V0216-9.jpg\",\"contentUrl\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Kettenglieder_V0216-9.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"LocateRisk\"},\"image\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/locaterisk\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection des donn\u00e9es - LocateRisk","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/locaterisk.com\/fr\/datenschutz\/","og_locale":"fr_FR","og_type":"article","og_title":"Datenschutz - LocateRisk","og_description":"Datenschutzerkl\u00e4rung Wir freuen uns, dass Sie unsere Website besuchen. Uns ist der Schutz Ihrer Privatsph\u00e4re sehr wichtig und wir m\u00f6chten, dass Sie sich bei der Nutzung der Seiten sicher f\u00fchlen. Aus diesem Grund behandeln wir Ihre Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung. 1. Name und Anschrift des Verantwortlichen Verantwortlicher im Sinne [&hellip;]","og_url":"https:\/\/locaterisk.com\/fr\/datenschutz\/","og_site_name":"LocateRisk","article_modified_time":"2022-07-14T16:14:27+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Kettenglieder_Generisch_03-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/locaterisk.com\/datenschutz\/","url":"https:\/\/locaterisk.com\/datenschutz\/","name":"Protection des donn\u00e9es - LocateRisk","isPartOf":{"@id":"https:\/\/locaterisk.com\/de\/#website"},"datePublished":"2020-11-04T10:53:54+00:00","dateModified":"2022-07-14T16:14:27+00:00","breadcrumb":{"@id":"https:\/\/locaterisk.com\/datenschutz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/locaterisk.com\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/locaterisk.com\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/locaterisk.com\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/locaterisk.com\/de\/#website","url":"https:\/\/locaterisk.com\/de\/","name":"LocateRisk","description":"Mesurer et comparer la s\u00e9curit\u00e9 informatique","publisher":{"@id":"https:\/\/locaterisk.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/locaterisk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/locaterisk.com\/de\/#organization","name":"LocateRisk","url":"https:\/\/locaterisk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/locaterisk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Kettenglieder_V0216-9.jpg","contentUrl":"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Kettenglieder_V0216-9.jpg","width":1920,"height":1080,"caption":"LocateRisk"},"image":{"@id":"https:\/\/locaterisk.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/locaterisk\/"]}]}},"_links":{"self":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/pages\/840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/comments?post=840"}],"version-history":[{"count":146,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/pages\/840\/revisions"}],"predecessor-version":[{"id":4025,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/pages\/840\/revisions\/4025"}],"wp:attachment":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/media?parent=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}