{"id":9176,"date":"2026-07-14T21:05:19","date_gmt":"2026-07-14T21:05:19","guid":{"rendered":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/"},"modified":"2026-07-14T21:05:19","modified_gmt":"2026-07-14T21:05:19","slug":"microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040","status":"publish","type":"post","link":"https:\/\/locaterisk.com\/fr\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/","title":{"rendered":"Microsoft Entra ID &amp; Exchange\/SharePoint : plusieurs failles de s\u00e9curit\u00e9 critiques (CVE-2026-55008, CVE-2026-56164, CVE-2026-55040)"},"content":{"rendered":"<div class=\"wp-block-lr-blog-article-header-module\">\r\n    <div class=\"content\">\r\n\t\t<div class=\"headline\">\r\n\t\t\t<button class=\"to-blog-button\">Retour au blog                <a href=\"https:\/\/locaterisk.com\/fr\/blog\/\"><\/a>\r\n\t\t\t<\/button>\r\n\t\t\t\t\t<\/div>\r\n        <div class=\"main-content\">\r\n\t\t\t\t\t\t<!--\r\n            <div class=\"header\">\r\n                <h6> <\/h6>\r\n            <\/div>\r\n\t\t\t\t\t\t-->\r\n            <h1 class=\"title\">Microsoft Entra ID &amp; Exchange\/SharePoint : plusieurs failles de s\u00e9curit\u00e9 critiques (CVE-2026-55008, CVE-2026-56164, CVE-2026-55040)<\/h1>\r\n            <p class=\"paragraph\"><br><span class=\"lr-ai-disclosure\" style=\"display:block;margin:8px 0 28px;font-size:14px;line-height:1.4;color:#8b93a7;font-family:inherit;font-style:italic;\">Ce texte a \u00e9t\u00e9 g\u00e9n\u00e9r\u00e9 par l'intelligence artificielle (IA).<\/span>Le 13 juillet 2026, Microsoft a annonc\u00e9 un changement strat\u00e9gique concernant son syst\u00e8me de gestion des identit\u00e9s et des acc\u00e8s, Microsoft Entra ID. \u00c0 compter du 1er septembre 2026, les cl\u00e9s d'acc\u00e8s seront progressivement mises en place comme m\u00e9thode par d\u00e9faut pour l'authentification multifactorielle (MFA). L'objectif de cette mesure est de renforcer la s\u00e9curit\u00e9 des comptes gr\u00e2ce \u00e0 des proc\u00e9dures de connexion r\u00e9sistantes au phishing, tout en rempla\u00e7ant les m\u00e9thodes vuln\u00e9rables telles que les SMS et les appels vocaux.<br><br>Cette transition concerne toutes les organisations qui utilisent Microsoft Entra ID dans le cloud public. Des calendriers distincts seront communiqu\u00e9s pour les autres environnements cloud. L'annonce officielle de Microsoft est disponible dans le Centre de messages Microsoft 365 \u00e0 l'adresse <strong>MC1426371<\/strong> disponible.<br><br><strong>Mise \u00e0 jour du 14 juillet 2026 :<\/strong> Par ailleurs, plusieurs vuln\u00e9rabilit\u00e9s critiques ont \u00e9t\u00e9 signal\u00e9es dans Microsoft Exchange Server, SharePoint Server et Active Directory Federation Services. La vuln\u00e9rabilit\u00e9 CVE-2026-55008 (CVSS 9,6) affecte Exchange Server et permet l'ex\u00e9cution de code \u00e0 distance. Les vuln\u00e9rabilit\u00e9s CVE-2026-56164 et CVE-2026-56155 sont des failles \u00ab zero-day \u00bb activement exploit\u00e9es dans SharePoint et AD FS. La vuln\u00e9rabilit\u00e9 CVE-2026-55040 (CVSS 9,1) permet de contourner l'authentification via la falsification de jetons JWT dans AD FS. Voir ci-dessous pour plus de d\u00e9tails.<\/p>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n\r\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png\" alt=\"Microsoft Entra ID &amp; Exchange\/SharePoint: mehrere kritische Sicherheitsl\u00fccken (CVE-2026-55008, CVE-2026-56164, CVE-2026-55040)\" class=\"wp-image-9142\" srcset=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png 400w, https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory-300x300.png 300w, https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory-150x150.png 150w, https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory-12x12.png 12w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\"><strong>Aper\u00e7u des faits<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Les \u00ab passkeys \u00bb comme norme :<\/strong> \u00c0 compter du 1er septembre 2026, les utilisateurs seront invit\u00e9s \u00e0 enregistrer leurs cl\u00e9s d'acc\u00e8s ; cette mesure deviendra obligatoire \u00e0 compter du 1er f\u00e9vrier 2027.<\/li>\n\n\n\n<li><strong>Les SMS et les appels vocaux sont d\u00e9sactiv\u00e9s :<\/strong> Les services natifs de Microsoft pour l'authentification par SMS et vocale prendront fin le 1er f\u00e9vrier 2027. L'int\u00e9gration de solutions tierces via le Microsoft Security Store restera possible.<\/li>\n\n\n\n<li><strong>Plateforme concern\u00e9e :<\/strong> Microsoft Entra ID (cloud public).<\/li>\n\n\n\n<li><strong>Vuln\u00e9rabilit\u00e9 critique d'Exchange :<\/strong> La vuln\u00e9rabilit\u00e9 CVE-2026-55008 (CVSS 9,6) affecte Exchange Server 2016 CU23, 2019 CU14\/CU15 et l'\u00e9dition Abonnement RTM. Ex\u00e9cution de code \u00e0 distance possible sans authentification, interaction de l'utilisateur requise.<\/li>\n\n\n\n<li><strong>Vuln\u00e9rabilit\u00e9s \u00ab zero-day \u00bb de SharePoint activement exploit\u00e9es :<\/strong> Les vuln\u00e9rabilit\u00e9s CVE-2026-56164 (\u00e9l\u00e9vation de privil\u00e8ges) et CVE-2026-50661 concernent SharePoint Server 2016, 2019 et l'\u00e9dition par abonnement. Correctifs disponibles : 16.0.5561.1001, 16.0.10417.20175, 16.0.19725.20434.<\/li>\n\n\n\n<li><strong>Vuln\u00e9rabilit\u00e9s critiques d'AD FS :<\/strong> Les vuln\u00e9rabilit\u00e9s CVE-2026-56155 (contr\u00f4le d'acc\u00e8s insuffisant) et CVE-2026-55040 (CVSS 9.1, contournement d'une fonctionnalit\u00e9 de s\u00e9curit\u00e9 via la falsification d'un jeton JWT) concernent les services de f\u00e9d\u00e9ration Active Directory. La vuln\u00e9rabilit\u00e9 CVE-2026-55040 fait actuellement l'objet d'exploits actifs.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Le calendrier de la transition<\/strong><\/h2>\n\n\n\n<p>Afin de garantir une mise en \u0153uvre sans heurts, Microsoft a publi\u00e9 un plan de d\u00e9ploiement \u00e9chelonn\u00e9. Les administrateurs informatiques sont invit\u00e9s \u00e0 prendre note des dates suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00c0 compter du 1er ao\u00fbt 2026 :<\/strong> Une prise en charge via l'API sera disponible pour configurer une exclusion temporaire du d\u00e9ploiement des cl\u00e9s d'acc\u00e8s.<\/li>\n\n\n\n<li><strong>\u00c0 compter du 1er septembre 2026 :<\/strong> Lors de la connexion via l'authentification multifactorielle (MFA), les utilisateurs se voient proposer d'enregistrer une cl\u00e9 d'acc\u00e8s. \u00c0 ce stade, cette d\u00e9marche est encore facultative.<\/li>\n\n\n\n<li><strong>\u00c0 partir du 18 septembre 2026 :<\/strong> Microsoft publie des informations sur les op\u00e9rateurs de t\u00e9l\u00e9communications tiers pris en charge dans le Microsoft Security Store.<\/li>\n\n\n\n<li><strong>\u00c0 partir du 30 octobre 2026 :<\/strong> Les administrateurs peuvent configurer des services de t\u00e9l\u00e9communications propos\u00e9s par des fournisseurs tiers dans le Microsoft Security Store pour la connexion par SMS et par appel vocal.<\/li>\n\n\n\n<li><strong>\u00c0 compter du 1er f\u00e9vrier 2027 :<\/strong> Les services SMS et vocaux natifs de Microsoft vont \u00eatre d\u00e9sactiv\u00e9s. La demande d'enregistrement d'une cl\u00e9 d'acc\u00e8s deviendra obligatoire pour tous les utilisateurs concern\u00e9s et ne pourra plus \u00eatre ignor\u00e9e.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mesures \u00e0 prendre et options pour les administrateurs<\/strong><\/h2>\n\n\n\n<p>Les entreprises doivent adapter leurs strat\u00e9gies d'authentification \u00e0 ce nouveau cadre. La p\u00e9riode de transition, qui s'\u00e9tend jusqu'en f\u00e9vrier 2027, leur laisse le temps de pr\u00e9parer leurs processus internes et la communication destin\u00e9e aux utilisateurs.<\/p>\n\n\n\n<p>Les organisations qui continuent de recourir \u00e0 l'authentification par SMS ou vocale doivent se tourner vers des solutions tierces pouvant \u00eatre int\u00e9gr\u00e9es via le Microsoft Security Store. Microsoft recommande toutefois clairement de passer \u00e0 des m\u00e9thodes totalement r\u00e9sistantes au phishing.<\/p>\n\n\n\n<p>Les utilisateurs qui ont d\u00e9j\u00e0 recours \u00e0 des m\u00e9thodes s\u00e9curis\u00e9es telles que <strong>Windows Hello pour les entreprises<\/strong>, <strong>Cl\u00e9s de s\u00e9curit\u00e9 FIDO2<\/strong>, l'authentification par certificat ou les cartes \u00e0 puce ne sont pas concern\u00e9es par cette nouvelle demande d'enregistrement, selon Microsoft Learn.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vuln\u00e9rabilit\u00e9 critique dans Microsoft Exchange Server (CVE-2026-55008)<\/strong><\/h2>\n\n\n\n<p>Parall\u00e8lement \u00e0 la migration vers Passkey, une faille de s\u00e9curit\u00e9 critique dans Microsoft Exchange Server a \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9e le 14 juillet 2026. La vuln\u00e9rabilit\u00e9 CVE-2026-55008 a re\u00e7u un score CVSS de 9,6 et permet l'ex\u00e9cution de code \u00e0 distance via le r\u00e9seau.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>D\u00e9tails techniques<\/strong><\/h3>\n\n\n\n<p>Cette vuln\u00e9rabilit\u00e9 concerne les versions suivantes d'Exchange :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Microsoft Exchange Server 2016 - Mise \u00e0 jour cumulative 23<\/li>\n\n\n\n<li>Microsoft Exchange Server 2019 - Mise \u00e0 jour cumulative 14<\/li>\n\n\n\n<li>Microsoft Exchange Server 2019 - Mise \u00e0 jour cumulative 15<\/li>\n\n\n\n<li>Microsoft Exchange Server \u00c9dition Abonnement RTM<\/li>\n<\/ul>\n\n\n\n<p>Un attaquant peut exploiter cette vuln\u00e9rabilit\u00e9 sans authentification pr\u00e9alable (PR:N), mais cela n\u00e9cessite une interaction de l'utilisateur (UI:R). Le vecteur d'attaque est de type r\u00e9seau (AV:N) et pr\u00e9sente une faible complexit\u00e9 d'attaque (AC:L). En cas d\u2019exploitation r\u00e9ussie, des r\u00e9percussions importantes sur la confidentialit\u00e9, l\u2019int\u00e9grit\u00e9 et la disponibilit\u00e9 sont possibles (C:H\/I:H\/A:H). La port\u00e9e est \u201e modifi\u00e9e \u201c (S:C), ce qui signifie que les r\u00e9percussions peuvent s\u2019\u00e9tendre au-del\u00e0 du composant vuln\u00e9rable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9valuation et recommandations d'action<\/strong><\/h3>\n\n\n\n<p>\u00c0 la date de publication, le statut du correctif n'est pas connu. Aucune information n'est disponible concernant une exploitation active ou l'ajout \u00e0 la liste KEV de la CISA. Les organisations disposant de serveurs Exchange dans les versions concern\u00e9es doivent suivre en permanence l'avis du Microsoft Security Response Center disponible \u00e0 l'adresse https:\/\/msrc.microsoft.com\/update-guide\/vulnerability\/CVE-2026-55008 et installer en priorit\u00e9 les mises \u00e0 jour de s\u00e9curit\u00e9 disponibles.<\/p>\n\n\n\n<p>La combinaison d'un score CVSS \u00e9lev\u00e9, d'un vecteur d'attaque bas\u00e9 sur le r\u00e9seau et de la possibilit\u00e9 d'ex\u00e9cuter du code \u00e0 distance fait de la vuln\u00e9rabilit\u00e9 CVE-2026-55008 une menace critique pour les infrastructures Exchange. En attendant la mise \u00e0 disposition d'un correctif, les administrateurs devraient envisager des mesures compensatoires telles que la segmentation du r\u00e9seau, une surveillance renforc\u00e9e et des restrictions d'acc\u00e8s aux services Exchange.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vuln\u00e9rabilit\u00e9s \u00ab zero-day \u00bb activement exploit\u00e9es dans SharePoint Server (CVE-2026-56164, CVE-2026-50661)<\/strong><\/h2>\n\n\n\n<p>Le 14 juillet 2026, deux vuln\u00e9rabilit\u00e9s activement exploit\u00e9es dans Microsoft SharePoint Server ont \u00e9t\u00e9 r\u00e9v\u00e9l\u00e9es. CVE-2026-56164 est une vuln\u00e9rabilit\u00e9 de type \u00ab \u00e9l\u00e9vation de privil\u00e8ges \u00bb rendue possible par un manque d'authentification. CVE-2026-50661 est une autre vuln\u00e9rabilit\u00e9 de SharePoint Server dont les d\u00e9tails techniques n'ont pas encore \u00e9t\u00e9 enti\u00e8rement publi\u00e9s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Versions et correctifs concern\u00e9s<\/strong><\/h3>\n\n\n\n<p>Ces vuln\u00e9rabilit\u00e9s concernent les versions suivantes de SharePoint :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Microsoft SharePoint Server 2016 (toutes les versions) < 16.0.5561.1001)<\/li>\n\n\n\n<li>Microsoft SharePoint Server 2019 (toutes les versions) < 16.0.10417.20175)<\/li>\n\n\n\n<li>Microsoft SharePoint Server \u00c9dition Abonnement (toutes les versions) < 16.0.19725.20434)<\/li>\n<\/ul>\n\n\n\n<p>Microsoft a publi\u00e9 des mises \u00e0 jour de s\u00e9curit\u00e9 qui corrigent ces vuln\u00e9rabilit\u00e9s :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>SharePoint Server 2016 : mise \u00e0 jour vers la version 16.0.5561.1001<\/li>\n\n\n\n<li>SharePoint Server 2019 : mise \u00e0 jour vers la version 16.0.10417.20175<\/li>\n\n\n\n<li>SharePoint Server \u00c9dition Abonnement : mise \u00e0 jour vers la version 16.0.19725.20434<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Urgence et recommandations d'action<\/strong><\/h3>\n\n\n\n<p>Ces deux vuln\u00e9rabilit\u00e9s \u00e9tant activement exploit\u00e9es, il est essentiel d'installer imm\u00e9diatement les correctifs. Les organisations disposant de serveurs SharePoint doivent installer ces mises \u00e0 jour en priorit\u00e9 et renforcer la surveillance des activit\u00e9s suspectes jusqu'\u00e0 ce que tous les correctifs soient d\u00e9ploy\u00e9s. Ces vuln\u00e9rabilit\u00e9s permettent aux attaquants d'\u00e9tendre leurs privil\u00e8ges au sein de l'environnement SharePoint, ce qui peut entra\u00eener l'exfiltration de donn\u00e9es, des mouvements lat\u00e9raux sur le r\u00e9seau et d'autres compromissions.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vuln\u00e9rabilit\u00e9s critiques dans Active Directory Federation Services (CVE-2026-56155, CVE-2026-55040)<\/strong><\/h2>\n\n\n\n<p>Parall\u00e8lement aux vuln\u00e9rabilit\u00e9s de SharePoint, deux failles critiques ont \u00e9t\u00e9 d\u00e9couvertes dans Active Directory Federation Services (AD FS). CVE-2026-56155 est une vuln\u00e9rabilit\u00e9 li\u00e9e \u00e0 un contr\u00f4le d'acc\u00e8s insuffisant. CVE-2026-55040 est une faille particuli\u00e8rement critique de contournement des fonctionnalit\u00e9s de s\u00e9curit\u00e9, avec un score CVSS de 9,1.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>CVE-2026-55040 : contournement de l'authentification par falsification de jetons JWT<\/strong><\/h3>\n\n\n\n<p>La vuln\u00e9rabilit\u00e9 CVE-2026-55040 permet \u00e0 des attaquants de contourner l'authentification en cr\u00e9ant de faux jetons JWT (JSON Web Tokens). Cette vuln\u00e9rabilit\u00e9 est activement exploit\u00e9e et repr\u00e9sente une menace importante pour les organisations qui utilisent AD FS pour l'authentification f\u00e9d\u00e9r\u00e9e. Une attaque r\u00e9ussie permet un acc\u00e8s non autoris\u00e9 \u00e0 des ressources prot\u00e9g\u00e9es sans identifiants valides.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00c9valuation technique et recommandations d'action<\/strong><\/h3>\n\n\n\n<p>La combinaison d'un score CVSS \u00e9lev\u00e9 (9,1), d'une exploitation active et de la possibilit\u00e9 de contourner compl\u00e8tement l'authentification fait de CVE-2026-55040 l'une des vuln\u00e9rabilit\u00e9s les plus critiques de la derni\u00e8re mise \u00e0 jour de s\u00e9curit\u00e9 de Microsoft. Les organisations disposant d'une infrastructure AD FS doivent appliquer sans d\u00e9lai les correctifs disponibles et v\u00e9rifier leurs journaux d'authentification \u00e0 la recherche d'anomalies, en particulier d'\u00e9missions ou de validations inhabituelles de jetons JWT.<\/p>\n\n\n\n<p>En attendant la mise en \u0153uvre compl\u00e8te du correctif, les administrateurs devraient envisager les mesures correctives suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Surveillance renforc\u00e9e des \u00e9v\u00e9nements d'authentification AD FS<\/li>\n\n\n\n<li>R\u00e9vision et renforcement des directives de validation des jetons JWT<\/li>\n\n\n\n<li>Segmentation du r\u00e9seau pour restreindre l'acc\u00e8s aux serveurs AD FS<\/li>\n\n\n\n<li>Activation de facteurs d'authentification suppl\u00e9mentaires pour les ressources critiques<\/li>\n<\/ul>\n\n\n\n<p>La vuln\u00e9rabilit\u00e9 CVE-2026-56155 n\u00e9cessite \u00e9galement l'installation rapide d'un correctif, car un contr\u00f4le d'acc\u00e8s insuffisant dans AD FS peut entra\u00eener un acc\u00e8s non autoris\u00e9 aux services f\u00e9d\u00e9r\u00e9s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pertinence pour les organisations de la r\u00e9gion DACH<\/strong><\/h2>\n\n\n\n<p>Cette transition rev\u00eat une importance particuli\u00e8re pour les entreprises soumises \u00e0 la directive NIS 2 et les op\u00e9rateurs KRITIS en Allemagne : l'utilisation de m\u00e9thodes d'authentification r\u00e9sistantes au phishing r\u00e9pond aux exigences en mati\u00e8re de mesures de s\u00e9curit\u00e9 techniques pr\u00e9vues \u00e0 l'article 30 de la loi BSIG. Le BSI recommande explicitement les proc\u00e9dures bas\u00e9es sur FIDO2 et les cl\u00e9s d'acc\u00e8s (passkeys) comme m\u00e9thodes d'authentification forte. Les organisations qui utilisent Microsoft Entra ID comme service d\u2019identit\u00e9 central devraient \u00e9galement int\u00e9grer cette transition dans leur documentation des changements conforme au RGPD et v\u00e9rifier si la modification de l\u2019infrastructure d\u2019authentification n\u00e9cessite des \u00e9valuations internes des risques conform\u00e9ment \u00e0 la norme ISO 27001.<\/p>\n\n\n\n<p>La vuln\u00e9rabilit\u00e9 CVE-2026-55008 d'Exchange, ainsi que les vuln\u00e9rabilit\u00e9s de SharePoint et d'AD FS actuellement exploit\u00e9es, soulignent l'urgence d'une gestion globale de la s\u00e9curit\u00e9 Microsoft. Les organisations disposant de serveurs Exchange, d\u2019installations SharePoint ou d\u2019une infrastructure AD FS doivent int\u00e9grer ces vuln\u00e9rabilit\u00e9s dans leur \u00e9valuation des risques conform\u00e9ment \u00e0 la norme ISO 27001, annexe A, paragraphe 8.8 (gestion des vuln\u00e9rabilit\u00e9s), et les documenter. L'exploitation active des vuln\u00e9rabilit\u00e9s CVE-2026-56164, CVE-2026-50661 et CVE-2026-55040 n\u00e9cessite une pr\u00e9paration imm\u00e9diate \u00e0 la r\u00e9ponse aux incidents et l'installation prioritaire des correctifs.<\/p>\n\n\n\n<p>Les organisations soumises \u00e0 la directive NIS 2 doivent respecter l'obligation de signalement des incidents de s\u00e9curit\u00e9 : s'il existe des indices laissant supposer une exploitation r\u00e9ussie de failles \u00ab zero-day \u00bb, un signalement \u00e0 l'autorit\u00e9 de contr\u00f4le comp\u00e9tente peut s'av\u00e9rer n\u00e9cessaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Analyse du point de vue de l'EASM et du VRM<\/strong><\/h2>\n\n\n\n<p>Le changement des m\u00e9thodes d'authentification chez un fournisseur d'identit\u00e9 centralis\u00e9 tel que Microsoft a des r\u00e9percussions directes sur la surface d'attaque externe et la gestion des risques li\u00e9s aux fournisseurs.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gestion de la surface d'attaque externe (EASM) :<\/strong> Microsoft Entra ID est un service accessible depuis l'ext\u00e9rieur dont les portails d'authentification font partie de l'infrastructure num\u00e9rique d'une entreprise. Une plateforme EASM telle que LocateRisk identifie ces points de terminaison d'authentification expos\u00e9s ainsi que d'autres (par exemple pour les VPN ou les services cloud). Savoir quels syst\u00e8mes d\u00e9pendent d\u2019Entra ID est essentiel pour \u00e9valuer l\u2019impact de cette modification de politique sur votre propre situation en mati\u00e8re de s\u00e9curit\u00e9. Parall\u00e8lement, les serveurs Exchange, les instances SharePoint et les serveurs AD FS accessibles depuis l\u2019ext\u00e9rieur doivent \u00eatre identifi\u00e9s et v\u00e9rifi\u00e9s quant \u00e0 leur vuln\u00e9rabilit\u00e9 aux failles CVE-2026-55008, CVE-2026-56164, CVE-2026-50661, CVE-2026-56155 et CVE-2026-55040. L\u2019exploitation active de plusieurs de ces vuln\u00e9rabilit\u00e9s rend la surveillance continue de la surface d\u2019attaque externe particuli\u00e8rement cruciale.<\/li>\n\n\n\n<li><strong>Gestion des risques li\u00e9s aux fournisseurs (VRM) :<\/strong> Microsoft est un fournisseur essentiel pour la plupart des entreprises. Une modification contraignante des politiques de s\u00e9curit\u00e9 constitue un \u00e9v\u00e9nement pertinent dans le cadre de la gestion des risques li\u00e9s \u00e0 la cyber-cha\u00eene d'approvisionnement. Une surveillance continue dans le cadre du VRM permet de recenser ces modifications chez les partenaires strat\u00e9giques et de garantir la conformit\u00e9 de l\u2019entreprise \u00e0 des normes telles que NIS-2 ou ISO 27001, qui exigent une gestion active des risques li\u00e9s aux fournisseurs. Les vuln\u00e9rabilit\u00e9s d\u2019Exchange, de SharePoint et d\u2019AD FS soulignent la n\u00e9cessit\u00e9 de surveiller \u00e9galement les processus de gestion des correctifs pour les produits Microsoft critiques dans le contexte du VRM. La multiplication des vuln\u00e9rabilit\u00e9s critiques de type \u00ab zero-day \u00bb en peu de temps devrait inciter \u00e0 actualiser l\u2019\u00e9valuation des risques li\u00e9s \u00e0 Microsoft en tant que fournisseur et \u00e0 documenter la d\u00e9pendance vis-\u00e0-vis des produits Microsoft au sein de la cha\u00eene d\u2019approvisionnement.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Voici comment LocateRisk vous aide<\/strong><\/h2>\n\n\n\n<p>La plateforme LocateRisk vous offre la visibilit\u00e9 n\u00e9cessaire sur votre surface d'attaque externe et sur la situation de s\u00e9curit\u00e9 de vos fournisseurs. Identifiez tous les syst\u00e8mes externes qui s'appuient sur Microsoft Entra ID pour l'authentification et \u00e9valuez les performances de s\u00e9curit\u00e9 de vos partenaires technologiques critiques. Identifiez les serveurs Exchange, les instances SharePoint et les serveurs AD FS expos\u00e9s au sein de votre infrastructure afin de localiser et de hi\u00e9rarchiser rapidement les vuln\u00e9rabilit\u00e9s telles que CVE-2026-55008, CVE-2026-56164, CVE-2026-50661, CVE-2026-56155 et CVE-2026-55040.<\/p>\n\n\n\n<p>Notre solution \u201e Made in Germany \u201c est h\u00e9berg\u00e9e dans des centres de donn\u00e9es allemands certifi\u00e9s \u2014 con\u00e7ue conform\u00e9ment aux exigences du RGPD et pr\u00e9sentant des risques r\u00e9duits li\u00e9s \u00e0 l'exposition au Cloud Act am\u00e9ricain.<\/p>\n\n\n\n<p><a href=\"https:\/\/locaterisk.com\/fr\/demo-anfordern\/\" target=\"_blank\" rel=\"noreferrer noopener\">Demandez une analyse sans engagement de votre surface d'attaque.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sources et informations compl\u00e9mentaires<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Blog Microsoft Security (13 juillet 2026) :<\/strong> <a href=\"https:\/\/www.microsoft.com\/en-us\/security\/blog\/2026\/07\/13\/microsoft-entra-id-security-updates-passkeys-are-the-default-authentication-method-in-entra-id\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mises \u00e0 jour de s\u00e9curit\u00e9 de Microsoft Entra ID : les cl\u00e9s d'acc\u00e8s constituent d\u00e9sormais la m\u00e9thode d'authentification par d\u00e9faut dans Entra ID<\/a><\/li>\n\n\n\n<li><strong>Microsoft Learn :<\/strong> <a href=\"https:\/\/learn.microsoft.com\/en-us\/entra\/identity\/authentication\/concept-sms-voice-retirement\" target=\"_blank\" rel=\"noreferrer noopener\">Fin de la prise en charge des SMS et des appels vocaux pour l'authentification dans Microsoft Entra ID<\/a><\/li>\n\n\n\n<li><strong>BleepingComputer (14 juillet 2026) :<\/strong> <a href=\"https:\/\/www.bleepingcomputer.com\/news\/microsoft\/microsoft-entra-id-gets-passkeys-default-authentication-starting-september\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c0 partir de septembre, Microsoft Entra ID adoptera les cl\u00e9s d'acc\u00e8s comme m\u00e9thode d'authentification par d\u00e9faut<\/a><\/li>\n\n\n\n<li><strong>Centre de r\u00e9ponse aux incidents de s\u00e9curit\u00e9 de Microsoft :<\/strong> <a href=\"https:\/\/msrc.microsoft.com\/update-guide\/vulnerability\/CVE-2026-55008\" target=\"_blank\" rel=\"noreferrer noopener\">Guide de mise \u00e0 jour de s\u00e9curit\u00e9 CVE-2026-55008<\/a><\/li>\n\n\n\n<li><strong>Centre de r\u00e9ponse aux incidents de s\u00e9curit\u00e9 de Microsoft :<\/strong> <a href=\"https:\/\/msrc.microsoft.com\/update-guide\/vulnerability\/CVE-2026-56164\" target=\"_blank\" rel=\"noreferrer noopener\">Guide de mise \u00e0 jour de s\u00e9curit\u00e9 CVE-2026-56164<\/a><\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-lr-faq-module\"><div class=\"content\"><h3><strong>Questions fr\u00e9quentes<\/strong><\/h3><div class=\"faq-topic\"><hr\/><div class=\"collapsible-title\"><a class=\"pr-4\"><strong>Qui est concern\u00e9 par le passage \u00e0 Microsoft Entra ID Passkeys ?<\/strong><\/a><img class=\"collapse-toggle\" srcset=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@3x.png 3x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@2x.png 2x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus.png 1x\"\/><\/div><div class=\"collapsible-content\"><p class=\"font-normal\">Toutes les organisations et tous les utilisateurs qui utilisent Microsoft Entra ID dans le cloud public. Les utilisateurs qui utilisent d\u00e9j\u00e0 une autre m\u00e9thode d'authentification r\u00e9sistante au phishing, telle que Windows Hello for Business, les cl\u00e9s de s\u00e9curit\u00e9 FIDO2 ou les cartes \u00e0 puce, font exception : selon Microsoft Learn, ceux-ci ne recevront pas de nouvelle demande d'enregistrement.<\/p><\/div><\/div><div class=\"faq-topic\"><hr\/><div class=\"collapsible-title\"><a class=\"pr-4\"><strong>Pourrai-je continuer \u00e0 envoyer des SMS et \u00e0 passer des appels vocaux apr\u00e8s le 1er f\u00e9vrier 2027 ?<\/strong><\/a><img class=\"collapse-toggle\" srcset=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@3x.png 3x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@2x.png 2x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus.png 1x\"\/><\/div><div class=\"collapsible-content\"><p class=\"font-normal\">Oui, l'utilisation reste possible, mais plus via le service natif de Microsoft. Pour cela, les entreprises doivent int\u00e9grer un fournisseur tiers de services de t\u00e9l\u00e9communications pris en charge via le Microsoft Security Store. La configuration sera possible \u00e0 partir du 30 octobre 2026 ; Microsoft publiera des informations sur les fournisseurs disponibles \u00e0 partir du 18 septembre 2026.<\/p><\/div><\/div><div class=\"faq-topic\"><hr\/><div class=\"collapsible-title\"><a class=\"pr-4\"><strong>Que se passe-t-il si les utilisateurs ne proc\u00e8dent pas \u00e0 l'enregistrement de leur cl\u00e9 d'acc\u00e8s ?<\/strong><\/a><img class=\"collapse-toggle\" srcset=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@3x.png 3x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@2x.png 2x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus.png 1x\"\/><\/div><div class=\"collapsible-content\"><p class=\"font-normal\">Entre le 1er septembre 2026 et le 1er f\u00e9vrier 2027, les utilisateurs pourront ignorer cette invite. Pass\u00e9 cette date butoir, la bo\u00eete de dialogue d'enregistrement deviendra obligatoire. Les utilisateurs concern\u00e9s ne pourront alors plus s'inscrire sans interagir avec cette invite.<\/p><\/div><\/div><div class=\"faq-topic\"><hr\/><div class=\"collapsible-title\"><a class=\"pr-4\"><strong>Mes serveurs Exchange sont-ils concern\u00e9s par la vuln\u00e9rabilit\u00e9 CVE-2026-55008 ?<\/strong><\/a><img class=\"collapse-toggle\" srcset=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@3x.png 3x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@2x.png 2x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus.png 1x\"\/><\/div><div class=\"collapsible-content\"><p class=\"font-normal\">V\u00e9rifiez si vous utilisez l'une des versions concern\u00e9es : Exchange Server 2016 CU23, Exchange Server 2019 CU14 ou CU15, ou Exchange Server Subscription Edition RTM. Consultez r\u00e9guli\u00e8rement le site du Microsoft Security Response Center pour obtenir des informations sur les correctifs et appliquez imm\u00e9diatement les mises \u00e0 jour disponibles.<\/p><\/div><\/div><div class=\"faq-topic\"><hr\/><div class=\"collapsible-title\"><a class=\"pr-4\"><strong>Dans quelle mesure l'installation des correctifs SharePoint est-elle urgente ?<\/strong><\/a><img class=\"collapse-toggle\" srcset=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@3x.png 3x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@2x.png 2x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus.png 1x\"\/><\/div><div class=\"collapsible-content\"><p class=\"font-normal\">Cette mise \u00e0 jour est critique et doit \u00eatre install\u00e9e imm\u00e9diatement. Les vuln\u00e9rabilit\u00e9s CVE-2026-56164 et CVE-2026-50661 font actuellement l'objet d'attaques. Les organisations disposant de serveurs SharePoint dans les versions concern\u00e9es (&lt; 16.0.5561.1001 pour 2016, &lt; 16.0.10417.20175 pour 2019, &lt; 16.0.19725.20434 pour l&#039;\u00e9dition par abonnement) devraient installer ces mises \u00e0 jour en priorit\u00e9.<\/p><\/div><\/div><div class=\"faq-topic\"><hr\/><div class=\"collapsible-title\"><a class=\"pr-4\"><strong>Quelles sont les implications de la vuln\u00e9rabilit\u00e9 CVE-2026-55040 pour mon infrastructure AD FS ?<\/strong><\/a><img class=\"collapse-toggle\" srcset=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@3x.png 3x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus@2x.png 2x,https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/faq-module\/img\/ic-plus.png 1x\"\/><\/div><div class=\"collapsible-content\"><p class=\"font-normal\">CVE-2026-55040 est une vuln\u00e9rabilit\u00e9 critique (CVSS 9.1) qui fait actuellement l'objet d'exploits et qui permet de contourner l'authentification par falsification de jetons JWT. Les organisations utilisant AD FS doivent installer imm\u00e9diatement les correctifs disponibles, v\u00e9rifier leurs journaux d'authentification \u00e0 la recherche d'anomalies et mettre en \u0153uvre des mesures correctives telles qu'une surveillance renforc\u00e9e et la segmentation du r\u00e9seau.<\/p><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-lr-contact-post-module\">\n\t<div id=\"lr-contact-form\" class=\"wp-block-lr-contact-post-module\">\n\t\t<div id=\"formular\" class=\"content\">\n\t\t\t<div class=\"inner-content\">\n\t\t\t\t<div class=\"column-2 feature-mode\">\n\t\t\t\t\t<h2><br>Demandez maintenant une D\u00e9mo en direct personelle<\/h2>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div>\n\t\t\t\t\t\t\t\t<p class=\"margin-b-36\">Identifiez et r\u00e9duisez vos cyber-risques gr\u00e2ce \u00e0 un aper\u00e7u comparable et compr\u00e9hensible de votre s\u00e9curit\u00e9 informatique. Demandez conseil \u00e0 nos experts et d\u00e9couvrez comment LocateRisk peut vous aider \u00e0 r\u00e9soudre vos cyber-risques.<\/p>\n\t\t\t\t\t\t\t<\/div>\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div> \n\t\t\t\t<div class=\"column-2\">\n\t\t\t\t\t<form action=\"\" class=\"form\" method=\"post\" role=\"form\" novalidate data-trp-original-action=\"\">\n\t\t\t\t\t\t<input type=\"text\" id=\"successmessage\" name=\"successmessage\" value=\"Ihre Registrierung war erfolgreich Ihre Anfrage wurde erfolgreich versendet. Wir haben Ihnen soeben eine Best\u00e4tigungsmail mit einem Aktivierungs-Link zugesendet, um einem Missbrauch Ihrer E-Mail Adresse durch Dritte vorzubeugen. Die Mail wird von sales@locaterisk.com versendet und sollte sich i n wenigen Minuten in Ihrem Posteingang finden.\" hidden>\n\t\t\t\t\t\t<input type=\"text\" id=\"errormessage\" name=\"errormessage\" value=\"Da ist wohl etwas schief gelaufen. Bitte probieren Sie es erneut oder nehmen Sie direkt mit uns Kontakt auf\" hidden>\n\t\t\t\t\t\t<input type=\"text\" id=\"slug\" name=\"slug\" value=\"microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\" hidden>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\t\ttype=\"text\"\n\t\t\t\t\t\t\t\tid=\"name\"\n\t\t\t\t\t\t\t\tname=\"name\"\n\t\t\t\t\t\t\t\tplaceholder=\"Pr\u00e9nom\"\n\t\t\t\t\t\t\t\trequired\tmaxlength=\"50\"\/>\n\n\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\t\ttype=\"text\"\n\t\t\t\t\t\t\t\tid=\"surname\"\n\t\t\t\t\t\t\t\tname=\"surname\"\n\t\t\t\t\t\t\t\tplaceholder=\"Nom\"\n\t\t\t\t\t\t\t\trequired\n\t\t\t\t\t\t\t\tmaxlength=\"50\"\/>\n\t\t\t\t\t\t\n\t\t\t\t\t\t<input\n\t\t\t\t\t\t\ttype=\"email\"\n\t\t\t\t\t\t\tid=\"email\"\n\t\t\t\t\t\t\tname=\"email\"\n\t\t\t\t\t\t\tplaceholder=\"Courrier \u00e9lectronique\"\n\t\t\t\t\t\t\trequired\n\t\t\t\t\t\t\tmaxlength=\"50\"\/>\n\n\t\t\t\t\t\t<input\n\t\t\t\t\t\t\ttype=\"text\"\n\t\t\t\t\t\t\tid=\"phone\"\n\t\t\t\t\t\t\tname=\"phone\"\n\t\t\t\t\t\t\tplaceholder=\"T\u00e9l\u00e9phone\"\n\t\t\t\t\t\t\trequired\n\t\t\t\t\t\t\tmaxlength=\"50\"\/>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h6 class=\"error-message\" hidden>...<\/h6>\n\t\t\t\t\t\t<div class=\"checkbox_container\">\n\t\t\t\t\t\t\t<div class=\"checkbox\">\n\t\t\t\t\t\t\t\t<input\n\t\t\t\t\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\t\t\t\t\tid=\"checkbox\"\n\t\t\t\t\t\t\t\t\tname=\"checkbox\" \/>\n\n\t\t\t\t\t\t\t\t<label for=\"checkbox\"><\/label>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<p class=\"translation-block\">Je suis d'accord avec la politique de confidentialit\u00e9<\/p> \n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"g-recaptcha\" data-sitekey=\"6LdErNoZAAAAAD1Re2jNxtDFfcDaL9iED5MRBzjR\" data-callback=\"verifyRecaptchaCallback\" data-expired-callback=\"expiredRecaptchaCallback\"><\/div>\n\t\t\t\t\t<input type=\"hidden\" name=\"g-recaptcha-response\" data-recaptcha \/>\n\n\t\t\t\t\t\t<button class=\"lr-button-link\" type=\"submit\"> Demander une d\u00e9mo<\/button>\n\t\t\t\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n\n\n\n<div class=\"wp-block-lr-contact-module\"><div class=\"content\"><h2>En savoir plus, r\u00e9server une d\u00e9mo ou simplement \u00e9changer quelques mots ? Nous nous en r\u00e9jouissons !<\/h2><div class=\"contact-info-row\"><div class=\"contact-person-info\"><div class=\"avatar\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2025\/06\/Lukas_Baumann_LocateRisk-300.png\"><\/div><p><span class=\"text before\">Votre Contact<\/span><span class=\"bold name\"><strong>Lukas<\/strong><\/span> <span class=\"lastname\"><strong>Baumann<strong><\/strong><\/strong><\/span><strong><strong><span class=\"separator\"><\/span><span class=\"role\">PDG<\/span><\/strong><\/strong><\/p><\/div><p class=\"bold phone\"><strong><strong>+49 6151 6290246<\/strong><\/strong><\/p><strong><strong><a class=\"pr-1\" href=\"mailto: sales@locaterisk.com\">Contactez-nous maintenant<\/a><\/strong><\/strong><\/div><\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-lr-footer-module lr-footer-block\"><div class=\"content\"><div class=\"column0\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/plugins\/locate-risk-prod\/lr-blocks\/assets\/img\/lr-logo.svg\"\/><\/div><div class=\"categories\"><div class=\"categories-element\"><a class=\"pr-4\" href=\"https:\/\/locaterisk.com\/fr\/\">Accueil<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/blog\/\">Blog<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/about\/\">par rapport \u00e0 nous<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/kontakt\/\">Contact<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/impressum\/\">mentiones l\u00e9gales<\/a><\/div><div class=\"categories-break\"><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/datenschutz\/\">Confidentialit\u00e9<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/files\/agb.pdf\">CONDITIONS G\u00c9N\u00c9RALES DE VENTE<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"\/fr\/jobs\/\">Carri\u00e8re<\/a><\/div><div class=\"categories-element\"><a class=\"pr-4\" href=\"https:\/\/app.secfix.com\/trust\/locaterisk\/d1e7d433b33643aea1880bfbfeab9f60\">Centre de confiance<\/a><\/div><\/div><div class=\"social\"><div class=\"social-element\"><a target=\"_blank\" href=\"https:\/\/www.linkedin.com\/company\/locaterisk\/\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/10\/gruppe-230@3x.png\"\/><\/a><\/div><div class=\"social-element\"><a target=\"_blank\" href=\"https:\/\/www.instagram.com\/locaterisk\/\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Instagram.png\"\/><\/a><\/div><div class=\"social-element\"><a target=\"_blank\" href=\"https:\/\/twitter.com\/locaterisk\"><img decoding=\"async\" src=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/twitter.png\"\/><\/a><\/div><\/div><div class=\"description\"><h6>\u00a9 LocateRisk 2026<\/h6><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Microsoft Entra ID adopte les cl\u00e9s d'acc\u00e8s comme norme. Parall\u00e8lement, des failles critiques de type \u00ab zero-day \u00bb ont \u00e9t\u00e9 signal\u00e9es dans SharePoint (CVE-2026-56164), AD FS (CVE-2026-55040, CVSS 9.1) et Exchange (CVE-2026-55008). Des mises \u00e0 jour sont disponibles.<\/p>","protected":false},"author":13,"featured_media":9142,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Microsoft Entra ID, Exchange &amp; SharePoint \u2013 kritische L\u00fccken<\/title>\n<meta name=\"description\" content=\"Microsoft Entra ID f\u00fchrt Passkeys als Standard ein. Parallel wurden kritische Zero-Days in SharePoint (CVE-2026-56164) und AD FS (CVE-2026-55040, CVSS 9.1) sowie Exchange (CVE-2026-55008) bekannt. Updates verf\u00fcgbar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/locaterisk.com\/fr\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Microsoft Entra ID, Exchange &amp; SharePoint \u2013 kritische L\u00fccken\" \/>\n<meta property=\"og:description\" content=\"Microsoft Entra ID f\u00fchrt Passkeys als Standard ein. Parallel wurden kritische Zero-Days in SharePoint (CVE-2026-56164) und AD FS (CVE-2026-55040, CVSS 9.1) sowie Exchange (CVE-2026-55008) bekannt. Updates verf\u00fcgbar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/locaterisk.com\/fr\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/\" \/>\n<meta property=\"og:site_name\" content=\"LocateRisk\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T21:05:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kristina Hoinkis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kristina Hoinkis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/\"},\"author\":{\"name\":\"Kristina Hoinkis\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#\\\/schema\\\/person\\\/68f3857c15afa8ff59c545848dddcc32\"},\"headline\":\"Microsoft Entra ID &#038; Exchange\\\/SharePoint: mehrere kritische Sicherheitsl\u00fccken (CVE-2026-55008, CVE-2026-56164, CVE-2026-55040)\",\"datePublished\":\"2026-07-14T21:05:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/\"},\"wordCount\":2093,\"publisher\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/compliance-regulatory.png\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/\",\"name\":\"Microsoft Entra ID, Exchange & SharePoint \u2013 kritische L\u00fccken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/compliance-regulatory.png\",\"datePublished\":\"2026-07-14T21:05:19+00:00\",\"description\":\"Microsoft Entra ID f\u00fchrt Passkeys als Standard ein. Parallel wurden kritische Zero-Days in SharePoint (CVE-2026-56164) und AD FS (CVE-2026-55040, CVSS 9.1) sowie Exchange (CVE-2026-55008) bekannt. Updates verf\u00fcgbar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/#primaryimage\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/compliance-regulatory.png\",\"contentUrl\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/compliance-regulatory.png\",\"width\":400,\"height\":400,\"caption\":\"compliance-regulatory\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/locaterisk.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Microsoft Entra ID &#038; Exchange\\\/SharePoint: mehrere kritische Sicherheitsl\u00fccken (CVE-2026-55008, CVE-2026-56164, CVE-2026-55040)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/\",\"name\":\"LocateRisk\",\"description\":\"IT-Sicherheit messen und vergleichen\",\"publisher\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#organization\",\"name\":\"LocateRisk\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Kettenglieder_V0216-9.jpg\",\"contentUrl\":\"https:\\\/\\\/locaterisk.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Kettenglieder_V0216-9.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"LocateRisk\"},\"image\":{\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/locaterisk\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/locaterisk.com\\\/de\\\/#\\\/schema\\\/person\\\/68f3857c15afa8ff59c545848dddcc32\",\"name\":\"Kristina Hoinkis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7756f96249844e60ceb218f17e06217dcbed4993bcd2124e3f59bb8675324f0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7756f96249844e60ceb218f17e06217dcbed4993bcd2124e3f59bb8675324f0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7756f96249844e60ceb218f17e06217dcbed4993bcd2124e3f59bb8675324f0d?s=96&d=mm&r=g\",\"caption\":\"Kristina Hoinkis\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Microsoft Entra ID, Exchange et SharePoint \u2013 failles critiques","description":"Microsoft Entra ID adopte les cl\u00e9s d'acc\u00e8s comme norme. Parall\u00e8lement, des failles critiques de type \u00ab zero-day \u00bb ont \u00e9t\u00e9 signal\u00e9es dans SharePoint (CVE-2026-56164), AD FS (CVE-2026-55040, CVSS 9.1) et Exchange (CVE-2026-55008). Des mises \u00e0 jour sont disponibles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/locaterisk.com\/fr\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/","og_locale":"fr_FR","og_type":"article","og_title":"Microsoft Entra ID, Exchange & SharePoint \u2013 kritische L\u00fccken","og_description":"Microsoft Entra ID f\u00fchrt Passkeys als Standard ein. Parallel wurden kritische Zero-Days in SharePoint (CVE-2026-56164) und AD FS (CVE-2026-55040, CVSS 9.1) sowie Exchange (CVE-2026-55008) bekannt. Updates verf\u00fcgbar.","og_url":"https:\/\/locaterisk.com\/fr\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/","og_site_name":"LocateRisk","article_published_time":"2026-07-14T21:05:19+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png","type":"image\/png"}],"author":"Kristina Hoinkis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Kristina Hoinkis","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/#article","isPartOf":{"@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/"},"author":{"name":"Kristina Hoinkis","@id":"https:\/\/locaterisk.com\/de\/#\/schema\/person\/68f3857c15afa8ff59c545848dddcc32"},"headline":"Microsoft Entra ID &#038; Exchange\/SharePoint: mehrere kritische Sicherheitsl\u00fccken (CVE-2026-55008, CVE-2026-56164, CVE-2026-55040)","datePublished":"2026-07-14T21:05:19+00:00","mainEntityOfPage":{"@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/"},"wordCount":2093,"publisher":{"@id":"https:\/\/locaterisk.com\/de\/#organization"},"image":{"@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/#primaryimage"},"thumbnailUrl":"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png","articleSection":["Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/","url":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/","name":"Microsoft Entra ID, Exchange et SharePoint \u2013 failles critiques","isPartOf":{"@id":"https:\/\/locaterisk.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/#primaryimage"},"image":{"@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/#primaryimage"},"thumbnailUrl":"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png","datePublished":"2026-07-14T21:05:19+00:00","description":"Microsoft Entra ID adopte les cl\u00e9s d'acc\u00e8s comme norme. Parall\u00e8lement, des failles critiques de type \u00ab zero-day \u00bb ont \u00e9t\u00e9 signal\u00e9es dans SharePoint (CVE-2026-56164), AD FS (CVE-2026-55040, CVSS 9.1) et Exchange (CVE-2026-55008). Des mises \u00e0 jour sont disponibles.","breadcrumb":{"@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/#primaryimage","url":"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png","contentUrl":"https:\/\/locaterisk.com\/wp-content\/uploads\/2026\/07\/compliance-regulatory.png","width":400,"height":400,"caption":"compliance-regulatory"},{"@type":"BreadcrumbList","@id":"https:\/\/locaterisk.com\/de\/microsoft-entra-id-exchange-sharepoint-mehrere-kritische-sicherheitsluecken-cve-2026-55008-cve-2026-56164-cve-2026-55040\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/locaterisk.com\/"},{"@type":"ListItem","position":2,"name":"Microsoft Entra ID &#038; Exchange\/SharePoint: mehrere kritische Sicherheitsl\u00fccken (CVE-2026-55008, CVE-2026-56164, CVE-2026-55040)"}]},{"@type":"WebSite","@id":"https:\/\/locaterisk.com\/de\/#website","url":"https:\/\/locaterisk.com\/de\/","name":"LocateRisk","description":"Mesurer et comparer la s\u00e9curit\u00e9 informatique","publisher":{"@id":"https:\/\/locaterisk.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/locaterisk.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/locaterisk.com\/de\/#organization","name":"LocateRisk","url":"https:\/\/locaterisk.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/locaterisk.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Kettenglieder_V0216-9.jpg","contentUrl":"https:\/\/locaterisk.com\/wp-content\/uploads\/2020\/11\/Kettenglieder_V0216-9.jpg","width":1920,"height":1080,"caption":"LocateRisk"},"image":{"@id":"https:\/\/locaterisk.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/locaterisk\/"]},{"@type":"Person","@id":"https:\/\/locaterisk.com\/de\/#\/schema\/person\/68f3857c15afa8ff59c545848dddcc32","name":"Kristina Hoinkis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7756f96249844e60ceb218f17e06217dcbed4993bcd2124e3f59bb8675324f0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7756f96249844e60ceb218f17e06217dcbed4993bcd2124e3f59bb8675324f0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7756f96249844e60ceb218f17e06217dcbed4993bcd2124e3f59bb8675324f0d?s=96&d=mm&r=g","caption":"Kristina Hoinkis"}}]}},"_links":{"self":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/posts\/9176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/comments?post=9176"}],"version-history":[{"count":0,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/posts\/9176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/media\/9142"}],"wp:attachment":[{"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/media?parent=9176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/categories?post=9176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/locaterisk.com\/fr\/wp-json\/wp\/v2\/tags?post=9176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}